
{"id":20525,"date":"2024-10-23T16:45:51","date_gmt":"2024-10-23T14:45:51","guid":{"rendered":"https:\/\/www.plantedforests.org\/?post_type=tribe_events&#038;p=20525"},"modified":"2025-01-27T15:29:09","modified_gmt":"2025-01-27T14:29:09","slug":"forem-2025","status":"publish","type":"tribe_events","link":"https:\/\/www.plantedforests.org\/pt\/event\/forem-2025\/","title":{"rendered":"FOREM 2025"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t1 Abril 2025\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t @ \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t08:00\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--end\">\n\t\t\t\t\t3 Abril 2025\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t\t\t @ \t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t\t17:00\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__timezone\">CEST<\/span>\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">FOREM (anciennement CAQSIS) est le r\u00e9seau d\u2019animation des chercheurs et d\u00e9veloppeurs francophones impliqu\u00e9s dans la mod\u00e9lisation des syst\u00e8mes FOR\u00caT-BOIS dans leurs environnements. Une r\u00e9union d\u2019\u00e9changes est organis\u00e9e chaque ann\u00e9e. Les membres du projet Capsis, plateforme de simulation pour les mod\u00e8les de croissance et de dynamique foresti\u00e8re, se r\u00e9unissent \u00e9galement \u00e0 cette occasion. Cette r\u00e9union est ouverte \u00e0 toute la communaut\u00e9 francophone int\u00e9ress\u00e9e par ces th\u00e9matiques, donc si vous le jugez opportun n&#8217;h\u00e9sitez pas \u00e0 diffuser l&#8217;annonce (voir les \u00e9ditions pr\u00e9c\u00e9dentes : <a href=\"https:\/\/capsis.cirad.fr\/capsis\/documentation#reports_of_capsisforem_annual_meetings\">https:\/\/capsis.cirad.fr\/capsis\/documentation#reports_of_capsisforem_annual_meetings<\/a> )<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">Cette ann\u00e9e, nous nous r\u00e9unirons \u00e0 Montpellier. Nous serons accueillis au CNRS par Xavier Morin du laboratoire CEFE. Gilles Le Moguedec (INRAE AMAP) participera \u00e9galement \u00e0 l\u2019organisation.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\"><strong>La r\u00e9union aura lieu dans la Grande Salle de r\u00e9union du CEFE (1er \u00e9tage, aile C), du mardi 1er avril 14:00 au jeudi 3 avril 17:00, soit 5 demi-journ\u00e9es, vous recevrez des autorisations d&#8217;acc\u00e8s personnalis\u00e9es au campus.<\/strong><br><br>CNRS CEFE<br>1919, route de Mende, 34293 Montpellier<br><br><strong>Le th\u00e8me de la session sp\u00e9ciale que nous vous proposons cette ann\u00e9e sera : Que peuvent nous dire les mod\u00e8les sur l\u2019impact du changement climatique sur les for\u00eats ?<\/strong><br><br>Toutes les propositions de contribution dans l&#8217;esprit FOREM, Capsis ou du th\u00e8me de la session sp\u00e9ciale sont accept\u00e9es pour ces journ\u00e9es. Les expos\u00e9s se feront en fran\u00e7ais (supports en anglais encourag\u00e9s).<br><br>Nous vous proposons deux types de contribution : soit un expos\u00e9 scientifique, soit une d\u00e9monstration interactive d\u2019outil (mod\u00e8le Capsis ou autre : introduction courte, puis d\u00e9monstration et discussion).<br><br>Selon le nombre de propositions, la dur\u00e9e des pr\u00e9sentations devrait \u00eatre de 20 \u00e0 25 minutes, incluant une p\u00e9riode de questions et celle des d\u00e9monstrations interactives devrait \u00eatre de 30 minutes. Un programme pr\u00e9liminaire sera publi\u00e9 fin mars avant la r\u00e9union.<br><br><strong>Le jeudi 4 avril apr\u00e8s-midi, nous vous proposerons une visite guid\u00e9e par J\u00e9rome Munzinger (IRD AMAP) du Jardin des Plantes de Montpellier.<\/strong><br><br><strong>Nous vous invitons donc \u00e0 vous inscrire en suivant ce lien avant le 7 mars au plus tard :<\/strong><br><br><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeJ7HSW0XwPNEgwM2PM3_QAc97GxtXMob-yOktevJDsbdhm3g\/viewform?usp=header\">https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeJ7HSW0XwPNEgwM2PM3_QAc97GxtXMob-yOktevJDsbdhm3g\/viewform?usp=header<\/a><br><br>Si vous proposez une contribution, pr\u00e9cisez nous son titre, ses auteurs et affiliations.<br><br><strong>L&#8217;inscription \u00e0 la r\u00e9union FOREM est gratuite. Les co\u00fbts de transport, de restauration et d&#8217;h\u00e9bergement sont \u00e0 la charge des participants.<\/strong><br><br><em>En cas de question, vous pouvez nous contacter par mail. FOREM (anciennement CAQSIS) est le r\u00e9seau d\u2019animation des chercheurs et d\u00e9veloppeurs francophones impliqu\u00e9s dans la mod\u00e9lisation des syst\u00e8mes FOR\u00caT-BOIS dans leurs environnements. Une r\u00e9union d\u2019\u00e9changes est organis\u00e9e chaque ann\u00e9e. Les membres du projet Capsis, plateforme de simulation pour les mod\u00e8les de croissance et de dynamique foresti\u00e8re, se r\u00e9unissent \u00e9galement \u00e0 cette occasion. Cette r\u00e9union est ouverte \u00e0 toute la communaut\u00e9 francophone int\u00e9ress\u00e9e par ces th\u00e9matiques, donc si vous le jugez opportun n&#8217;h\u00e9sitez pas \u00e0 diffuser l&#8217;annonce (voir les \u00e9ditions pr\u00e9c\u00e9dentes : <a href=\"https:\/\/capsis.cirad.fr\/capsis\/documentation#reports_of_capsisforem_annual_meetings\">https:\/\/capsis.cirad.fr\/capsis\/documentation#reports_of_capsisforem_annual_meetings<\/a> )<\/em><\/p>\n\n\n<div  class=\"tribe-block tribe-block__event-price\" >\n\t\t<\/div>\n\n\n\n\n<div  class=\"tribe-block tribe-block__venue tribe-clearfix\" >\n\t\n\t\t\n\t<\/div>\n\n\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"View links to add events to your calendar\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tAdicionar ao calend\u00e1rio\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20250401T080000\/20250403T170000&#038;text=FOREM%202025&#038;details=%3Cp+class%3D%22has-black-color+has-text-color+has-link-color%22%3EFOREM+%28anciennement+CAQSIS%29+est+le+r%C3%A9seau+d%E2%80%99animation+des+chercheurs+et+d%C3%A9veloppeurs+francophones+impliqu%C3%A9s+dans+la+mod%C3%A9lisation+des+syst%C3%A8mes+FOR%C3%8AT-BOIS+dans+leurs+environnements.+Une+r%C3%A9union+d%E2%80%99%C3%A9changes+est+organis%C3%A9e+chaque+ann%C3%A9e.+Les+membres+du+projet+Capsis%2C+plateforme+de+simulation+pour+les+mod%C3%A8les+de+croissance+et+de+dynamique+foresti%C3%A8re%2C+se+r%C3%A9unissent+%C3%A9galement+%C3%A0+cette+occasion.+Cette+r%C3%A9union+est+ouverte+%C3%A0+toute+la+communaut%C3%A9+francophone+int%C3%A9ress%C3%A9e+par+ces+th%C3%A9matiques%2C+donc+si+vous+le+jugez+opportun+n%27h%C3%A9sitez+pas+%C3%A0+diffuser+l%27annonce+%28voir+les+%C3%A9ditions+pr%C3%A9c%C3%A9dentes+%3A+%3Ca+href%3D%22https%3A%2F%2Fcapsis.cirad.fr%2Fcapsis%2Fdocumentation%23reports_of_capsisforem_annual_meetings%22%3Ehttps%3A%2F%2Fcapsis.cirad.fr%2Fcapsis%2Fdocumentation%23reports_of_capsisforem_annual_meetings%3C%2Fa%3E+%29%3C%2Fp%3E+%3Cp+class%3D%22has-black-color+has-text-color+has-link-color%22%3ECette+ann%C3%A9e%2C+nous+nous+r%C3%A9unirons+%C3%A0+Montpellier.+Nous+serons+accueillis+au+CN%3C%2Fp%3E+%28Veja+a+descri%C3%A7%C3%A3o+completa+de+evento+aqui%3A+https%3A%2F%2Fwww.plantedforests.org%2Fpt%2Fevent%2Fforem-2025%2F%29&#038;trp=false&#038;ctz=Europe\/Paris&#038;sprop=website:https:\/\/www.plantedforests.org\/pt\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tCalend\u00e1rio Google\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>FOREM (anciennement CAQSIS) est le r\u00e9seau d\u2019animation des chercheurs et d\u00e9veloppeurs francophones impliqu\u00e9s dans la mod\u00e9lisation des syst\u00e8mes FOR\u00caT-BOIS dans leurs environnements. Une r\u00e9union d\u2019\u00e9changes est organis\u00e9e chaque ann\u00e9e. Les [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"Europe\/Paris","_EventStartDate":"2025-04-01 08:00:00","_EventEndDate":"2025-04-03 17:00:00","_EventStartDateUTC":"2025-04-01 06:00:00","_EventEndDateUTC":"2025-04-03 15:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"EUR","_EventCurrencyPosition":"suffix","_EventDateTimeSeparator":" @ ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-20525","tribe_events","type-tribe_events","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"pt","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FOREM 2025 - Instituto Europeu De Floresta Plantada - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/event\/forem-2025\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FOREM 2025 - Instituto Europeu De Floresta Plantada - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/event\/forem-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Europeu De Floresta Plantada - IEFC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-27T14:29:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/event\\\/forem-2025\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/event\\\/forem-2025\\\/\",\"name\":\"FOREM 2025 - Instituto Europeu De Floresta Plantada - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"datePublished\":\"2024-10-23T14:45:51+00:00\",\"dateModified\":\"2025-01-27T14:29:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/event\\\/forem-2025\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/event\\\/forem-2025\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/event\\\/forem-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FOREM 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Instituto Europeu De Floresta Plantada - IEFC\",\"description\":\"A rede IEFC para a gest\u00e3o sustent\u00e1vel e resili\u00eancia das florestas cultivadas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FOREM 2025 - Instituto Europeu De Floresta Plantada - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/event\/forem-2025\/","og_locale":"pt_PT","og_type":"article","og_title":"FOREM 2025 - Instituto Europeu De Floresta Plantada - IEFC","og_url":"https:\/\/www.plantedforests.org\/event\/forem-2025\/","og_site_name":"Instituto Europeu De Floresta Plantada - IEFC","article_modified_time":"2025-01-27T14:29:09+00:00","twitter_card":"summary_large_image","twitter_site":"@IEFCPlantForest","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/event\/forem-2025\/","url":"https:\/\/www.plantedforests.org\/event\/forem-2025\/","name":"FOREM 2025 - Instituto Europeu De Floresta Plantada - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"datePublished":"2024-10-23T14:45:51+00:00","dateModified":"2025-01-27T14:29:09+00:00","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/event\/forem-2025\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/event\/forem-2025\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/event\/forem-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/www.plantedforests.org\/fr\/events\/"},{"@type":"ListItem","position":3,"name":"FOREM 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Instituto Europeu De Floresta Plantada - IEFC","description":"A rede IEFC para a gest\u00e3o sustent\u00e1vel e resili\u00eancia das florestas cultivadas","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/tribe_events\/20525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/users\/101"}],"version-history":[{"count":8,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/tribe_events\/20525\/revisions"}],"predecessor-version":[{"id":21756,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/tribe_events\/20525\/revisions\/21756"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/media?parent=20525"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/tags?post=20525"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/tribe_events_cat?post=20525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}