
{"id":13859,"date":"2023-09-27T10:35:57","date_gmt":"2023-09-27T08:35:57","guid":{"rendered":"https:\/\/www.plantedforests.org\/?p=13859"},"modified":"2023-10-16T13:41:31","modified_gmt":"2023-10-16T11:41:31","slug":"liefc-recrute","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/pt\/liefc-recrute\/","title":{"rendered":"l&#8217;IEFC Recrute"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#006633\"><em>L&#8217;Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#006633\"><em>est \u00e0 la recherche d&#8217;un<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#006633\"><strong>Expert Junior (H\/F) en am\u00e9nagement du territoire et implication des collectivit\u00e9s locales dans la gestion des risques d&#8217;incendie<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#006633\"><em>pour le projet FIRE-RES de l&#8217;UE et le soutien \u00e0 l&#8217;\u00e9change de connaissances<\/em><\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">L&#8217;IEFC (Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e) est une association europ\u00e9enne multi-acteurs regroupant 32 organisations membres et 10 membres associ\u00e9s.<br>Les locaux de l&#8217;IEFC sont situ\u00e9s dans l&#8217;attrayant Campus For\u00eat Bois du CESTAS, en France, \u00e0 proximit\u00e9 des villes de Bordeaux et d&#8217;Arcachon.<br>L&#8217;IEFC est g\u00e9r\u00e9 par une petite \u00e9quipe li\u00e9e \u00e0 de nombreuses organisations foresti\u00e8res mondiales telles que le r\u00e9seau mondial de l&#8217;IUFRO et nous avons d\u00e9j\u00e0 \u00e9t\u00e9 reconnus comme le r\u00e9seau de recherche d\u00e9di\u00e9 aux for\u00eats plant\u00e9es pour l&#8217;EFI (European Forest Institute).<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">L&#8217;IEFC a pour objectif de promouvoir et de mener des recherches sur la gestion durable des for\u00eats plant\u00e9es. L&#8217;IEFC offre un poste pour travailler dans les projets FIRES-RES o\u00f9 l&#8217;IEFC est responsable d&#8217;un laboratoire vivant pour am\u00e9liorer la r\u00e9silience des paysages aux m\u00e9ga-feux dans un contexte de changement climatique. Ce travail suppose une forte collaboration avec l&#8217;ARDFCI et les territoires impliqu\u00e9s dans le projet.<br>La langue de travail de l&#8217;Institut est le fran\u00e7ais et l&#8217;anglais.<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong>T\u00e2ches et responsabilit\u00e9s<\/strong><br>\u2022 Participation \u00e0 des \u00e9changes pour d\u00e9finir des options de paysages r\u00e9silients et d&#8217;interfaces urbaines r\u00e9silientes aux incendies<br>\u2022 Diffusion des r\u00e9sultats obtenus par le living lab. \u00e0 partir de la simulation<br>\u2022 Coordination de la gestion int\u00e9gr\u00e9e des incendies de for\u00eat et promotion des activit\u00e9s de br\u00fblage dirig\u00e9<br>\u2022 Incitation aux actions de formation sur la pr\u00e9vention<br>\u2022 Identification des activit\u00e9s \u00e9conomiques permettant de r\u00e9duire le risque d&#8217;incendie et d&#8217;analyser la viabilit\u00e9 et le meilleur positionnement dans le paysage<br>\u2022 Soutenir et promouvoir des outils pour am\u00e9liorer la culture de la gestion du risque incendie dans le bassin de vie des Landes de Gascogne en promouvant la gestion int\u00e9gr\u00e9e des territoires.<br>\u2022 Am\u00e9lioration des connaissances et des pratiques des collectivit\u00e9s locales et mise \u00e0 jour du guide pour les urbanistes prenant en compte le risque d&#8217;incendie de for\u00eat<br>\u2022 Soutien \u00e0 l&#8217;\u00e9v\u00e9nement sur les solutions innovantes en mati\u00e8re de pr\u00e9vention et de lutte contre les incendies qui doit \u00eatre organis\u00e9 dans le cadre du projet<\/p>\n<\/div>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong>Qualifications<\/strong><br>Ma\u00eetrise en sciences sociales, en am\u00e9nagement du territoire, en urbanisme, en d\u00e9veloppement rural et\/ou en pr\u00e9vention des incendies de for\u00eat ou dipl\u00f4me universitaire (ou une qualification comparable) dans un domaine appropri\u00e9.<br>Bonne connaissance des incendies de for\u00eat et de l&#8217;urbanisme.<br>La ma\u00eetrise du fran\u00e7ais est obligatoire. Une bonne connaissance de l&#8217;anglais est un atout.<br>Une solide exp\u00e9rience de la r\u00e9daction de synth\u00e8ses et de la vulgarisation des connaissances scientifiques est un atout.<br>Une bonne connaissance des collectivit\u00e9s locales et des outils de d\u00e9veloppement local (Scot, SRADET, \u2026) est un plus.<br>Une exp\u00e9rience en mati\u00e8re de consultation et de concertation est recommand\u00e9e.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong>Lieu d&#8217;affectation<\/strong><br>L&#8217;employ\u00e9 sera bas\u00e9 dans les locaux de l&#8217;IEFC \u00e0 l&#8217;INRA Bordeaux Centre \u00e0 Cestas, en France.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong>Conditions d&#8217;emploi<\/strong><br>L&#8217;employ\u00e9 sera un membre du personnel de l&#8217;IEFC sous contrat sous r\u00e9glementation priv\u00e9e fran\u00e7aise (\u00e0 temps plein ou \u00e0 temps partiel si souhait\u00e9). Le candidat retenu devrait prendre ses fonctions d\u00e8s que possible en 2023 d\u00e9but 2024\u2026.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Les candidats int\u00e9ress\u00e9s sont pri\u00e9s d&#8217;envoyer une lettre de candidature et un CV avec les pr\u00e9tentions salariales et une r\u00e9f\u00e9rence <strong><span style=\"text-decoration: underline;\">avant le 20 octobre 2023<\/span><\/strong>, par courriel \u00e0 rh[at]iefc.net. Un entretien pourrait \u00eatre n\u00e9cessaire.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Pour plus d&#8217;informations sur le poste, veuillez contacter M. Christophe Orazio, Directeur \u00e0 rh[at]iefc.net <\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e est \u00e0 la recherche d&#8217;un Expert Junior (H\/F) en am\u00e9nagement du territoire et implication des collectivit\u00e9s locales dans la gestion des risques d&#8217;incendie pour [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":13870,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1],"tags":[309],"class_list":["post-13859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives","tag-job-offer"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"pt","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>l&#039;IEFC Recrute - Instituto Europeu De Floresta Plantada - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/liefc-recrute\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;IEFC Recrute - Instituto Europeu De Floresta Plantada - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/liefc-recrute\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Europeu De Floresta Plantada - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-27T08:35:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-16T11:41:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/09\/LIEFC-Recrute-V2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comm IEFC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comm IEFC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/\"},\"author\":{\"name\":\"comm IEFC\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\"},\"headline\":\"l&#8217;IEFC Recrute\",\"datePublished\":\"2023-09-27T08:35:57+00:00\",\"dateModified\":\"2023-10-16T11:41:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/\"},\"wordCount\":674,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LIEFC-Recrute-V2.jpg\",\"keywords\":[\"job offer\"],\"articleSection\":[\"\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/\",\"name\":\"l'IEFC Recrute - Instituto Europeu De Floresta Plantada - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LIEFC-Recrute-V2.jpg\",\"datePublished\":\"2023-09-27T08:35:57+00:00\",\"dateModified\":\"2023-10-16T11:41:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LIEFC-Recrute-V2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LIEFC-Recrute-V2.jpg\",\"width\":1920,\"height\":568,\"caption\":\"Planted Forests Reports (Image de couverture d\u2019article LinkedIn) (1920\u00a0\u00d7\u00a01080\u00a0px) - English\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/liefc-recrute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"l&#8217;IEFC Recrute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Instituto Europeu De Floresta Plantada - IEFC\",\"description\":\"A rede IEFC para a gest\u00e3o sustent\u00e1vel e resili\u00eancia das florestas cultivadas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\",\"name\":\"comm IEFC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"caption\":\"comm IEFC\"},\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/author\\\/communication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"l'IEFC Recrute - Instituto Europeu De Floresta Plantada - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/liefc-recrute\/","og_locale":"pt_PT","og_type":"article","og_title":"l'IEFC Recrute - Instituto Europeu De Floresta Plantada - IEFC","og_url":"https:\/\/www.plantedforests.org\/liefc-recrute\/","og_site_name":"Instituto Europeu De Floresta Plantada - IEFC","article_published_time":"2023-09-27T08:35:57+00:00","article_modified_time":"2023-10-16T11:41:31+00:00","og_image":[{"width":1920,"height":568,"url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/09\/LIEFC-Recrute-V2.jpg","type":"image\/jpeg"}],"author":"comm IEFC","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"Escrito por":"comm IEFC","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/"},"author":{"name":"comm IEFC","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a"},"headline":"l&#8217;IEFC Recrute","datePublished":"2023-09-27T08:35:57+00:00","dateModified":"2023-10-16T11:41:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/"},"wordCount":674,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"image":{"@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/09\/LIEFC-Recrute-V2.jpg","keywords":["job offer"],"articleSection":[""],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/","url":"https:\/\/www.plantedforests.org\/liefc-recrute\/","name":"l'IEFC Recrute - Instituto Europeu De Floresta Plantada - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/#primaryimage"},"image":{"@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/09\/LIEFC-Recrute-V2.jpg","datePublished":"2023-09-27T08:35:57+00:00","dateModified":"2023-10-16T11:41:31+00:00","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/liefc-recrute\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/#primaryimage","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/09\/LIEFC-Recrute-V2.jpg","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/09\/LIEFC-Recrute-V2.jpg","width":1920,"height":568,"caption":"Planted Forests Reports (Image de couverture d\u2019article LinkedIn) (1920\u00a0\u00d7\u00a01080\u00a0px) - English"},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/liefc-recrute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/fr\/"},{"@type":"ListItem","position":2,"name":"l&#8217;IEFC Recrute"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Instituto Europeu De Floresta Plantada - IEFC","description":"A rede IEFC para a gest\u00e3o sustent\u00e1vel e resili\u00eancia das florestas cultivadas","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a","name":"comm IEFC","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","caption":"comm IEFC"},"url":"https:\/\/www.plantedforests.org\/pt\/author\/communication\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/posts\/13859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/comments?post=13859"}],"version-history":[{"count":9,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/posts\/13859\/revisions"}],"predecessor-version":[{"id":14151,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/posts\/13859\/revisions\/14151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/media\/13870"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/media?parent=13859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/categories?post=13859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/pt\/wp-json\/wp\/v2\/tags?post=13859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}