
{"id":5780,"date":"2022-03-09T09:13:12","date_gmt":"2022-03-09T08:13:12","guid":{"rendered":"https:\/\/www.iefc.net\/?p=5780"},"modified":"2023-08-25T11:36:18","modified_gmt":"2023-08-25T09:36:18","slug":"pine-wood-nematode-december-iufro-expert-groups-conclusion","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/","title":{"rendered":"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d&rsquo;experts de l&rsquo;IUFRO"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"171\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general-1024x171.jpg\" alt=\"\" class=\"wp-image-5781\" srcset=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general-1024x171.jpg 1024w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general-300x50.jpg 300w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general-150x25.jpg 150w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general-768x128.jpg 768w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general-1536x256.jpg 1536w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general-1320x220.jpg 1320w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En d\u00e9cembre dernier, l&rsquo;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.iufro.org\/\" target=\"_blank\">IUFRO <\/a>a organis\u00e9 le <a rel=\"noreferrer noopener\" href=\"https:\/\/symposium.inrae.fr\/pwd2020\/\" target=\"_blank\">symposium international de l&rsquo;IUFRO sur la maladie du fl\u00e9trissement du pin (\u00ab\u00a0PWD2020\u00a0\u00bb).<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cet \u00e9v\u00e9nement a \u00e9t\u00e9 l&rsquo;occasion de discuter du n\u00e9matode du pin et de ses d\u00e9g\u00e2ts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Originaire d&rsquo;Am\u00e9rique du Nord, le n\u00e9matode du pin, <em>Bursaphelenchus xylophilus<\/em>, a \u00e9t\u00e9 introduit accidentellement en Asie o\u00f9 il provoque des d\u00e9g\u00e2ts importants. Les d\u00e9g\u00e2ts vraisemblablement dus \u00e0 l&rsquo;infection par le n\u00e9matode ont commenc\u00e9 au Japon en 1905, puis le n\u00e9matode a \u00e9t\u00e9 effectivement d\u00e9tect\u00e9 quelques ann\u00e9es plus tard. Le n\u00e9matode a ensuite \u00e9t\u00e9 d\u00e9tect\u00e9 en Chine en 1982, sur l&rsquo;\u00eele de Taiwan en 1985 et en Cor\u00e9e en 1988. Il a \u00e9t\u00e9 d\u00e9tect\u00e9 pour la premi\u00e8re fois en Europe en 1999 pr\u00e8s de Lisbonne au Portugal, et depuis il s&rsquo;est r\u00e9pandu dans presque tout le pays, y compris sur l&rsquo;\u00eele portugaise de Mad\u00e8re en 2009, mais il a \u00e9galement \u00e9t\u00e9 d\u00e9tect\u00e9 dans diff\u00e9rents endroits en Espagne depuis 2008, mais a \u00e9t\u00e9 \u00e9radiqu\u00e9 \u00e0 chaque fois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La communaut\u00e9 scientifique \u00e9tudie ce n\u00e9matode pathog\u00e8ne envahissant, son insecte vecteur (<em>Monochamus<\/em> spp.), la sensibilit\u00e9 des pins, ainsi que les champignons et bact\u00e9ries associ\u00e9s. Cela n\u00e9cessite des approches multidisciplinaires r\u00e9unissant des experts en n\u00e9matologie, entomologie, r\u00e9sistance des arbres, \u00e9cologie, g\u00e9n\u00e9tique et mod\u00e9lisation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd&rsquo;hui, le n\u00e9matode du pin continue de se propager dans le monde. Par exemple, de nouvelles infestations ont \u00e9t\u00e9 d\u00e9couvertes (et font l\u2019objet d\u2019\u00e9radication) en Espagne et il continue de se propager en Chine. Mais en m\u00eame temps, il y a des r\u00e9sultats encourageants : au Portugal, gr\u00e2ce aux efforts de confinement, aucun n\u00e9matode du pin n&rsquo;a \u00e9t\u00e9 trouv\u00e9 dans la zone tampon \u00e9tablie le long de la fronti\u00e8re avec l&rsquo;Espagne, et la R\u00e9publique de Cor\u00e9e a signal\u00e9 une diminution de l&rsquo;occurrence du n\u00e9matode du pin et un succ\u00e8s relativement bon dans le confinement de la propagation avec un ensemble de mesures de contr\u00f4le et de surveillance. En outre, les dommages caus\u00e9s par le fl\u00e9trissement du pin semblent cesser naturellement dans certains endroits du nord-est du Japon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le symposium a \u00e9galement mis en \u00e9vidence le r\u00f4le des ports dans le risque d&rsquo;introduction, l&rsquo;importance du programme de s\u00e9lection g\u00e9n\u00e9tique pour fournir un ensemble de familles de <em>Pinus pinaster<\/em> r\u00e9sistantes ou tol\u00e9rantes, a pr\u00e9sent\u00e9 les interactions entre le n\u00e9matode, l&rsquo;insecte vecteur, les arbres h\u00f4tes, les champignons et les bact\u00e9ries. Enfin les participants ont relev\u00e9 le perfectionnement des outils de surveillance (conception des pi\u00e8ges et leurres, surveillance a\u00e9rienne avec des images satellites ou des drones pour d\u00e9tecter les arbres d\u00e9p\u00e9rissant) et le besoin de formation des professionnels de la for\u00eat&nbsp;&nbsp; &nbsp;pour mettre en \u0153uvre des pratiques limitant le risque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afin d&rsquo;\u00e9viter l&rsquo;\u00e9tablissement de la maladie du fl\u00e9trissement du pin, il est essentiel de mener une enqu\u00eate minutieuse dans les points chauds d&rsquo;entr\u00e9e (c&rsquo;est-\u00e0-dire les ports et les a\u00e9roports) pour d\u00e9tecter les signes de la pr\u00e9sence d&rsquo;insectes vecteurs exotiques dans les marchandises et la d\u00e9tection pr\u00e9coce des arbres d\u00e9p\u00e9rissant dans les zones foresti\u00e8res de conif\u00e8res environnantes. Il est essentiel de briser la cha\u00eene avant qu&rsquo;il ne soit trop tard. Le pi\u00e9geage des col\u00e9opt\u00e8res immatures infest\u00e9s serait important pour pr\u00e9venir la transmission du n\u00e9matode du pin, mais des recherches suppl\u00e9mentaires sont n\u00e9cessaires car, jusqu&rsquo;\u00e0 pr\u00e9sent, ils ne r\u00e9agissent pas aux app\u00e2ts disponibles. La possibilit\u00e9 d&rsquo;avoir des arbres asymptomatiques (latents) semble \u00e9galement tr\u00e8s importante \u00e0 consid\u00e9rer dans le succ\u00e8s de la gestion des n\u00e9matodes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plus de d\u00e9tails et d&rsquo;informations peuvent \u00eatre trouv\u00e9s sur le site de l&rsquo;IUFRO <a href=\"https:\/\/www.iufro.org\/science\/divisions\/division-7\/70000\/70200\/70210\/activities\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.iufro.org\/science\/divisions\/division-7\/70000\/70200\/70210\/activities\/<\/a> et sur le site du symposium : <a href=\"https:\/\/symposium.inrae.fr\/pwd2020\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/symposium.inrae.fr\/pwd2020\/<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En d\u00e9cembre dernier, l&rsquo;IUFRO a organis\u00e9 le symposium international de l&rsquo;IUFRO sur la maladie du fl\u00e9trissement du pin (\u00ab\u00a0PWD2020\u00a0\u00bb). Cet \u00e9v\u00e9nement a \u00e9t\u00e9 l&rsquo;occasion de discuter du n\u00e9matode du pin [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":5781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[236,230],"tags":[],"class_list":["post-5780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biotic","category-risk-management"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"fr","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d&#039;experts de l&#039;IUFRO  - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d&#039;experts de l&#039;IUFRO  - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/\" \/>\n<meta property=\"og:site_name\" content=\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-09T08:13:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:36:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comm IEFC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"comm IEFC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/\"},\"author\":{\"name\":\"comm IEFC\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\"},\"headline\":\"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d&rsquo;experts de l&rsquo;IUFRO\",\"datePublished\":\"2022-03-09T08:13:12+00:00\",\"dateModified\":\"2023-08-25T09:36:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/\"},\"wordCount\":2535,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Bandeau-general.jpg\",\"articleSection\":[\"Biotic\",\"Risk management\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/\",\"name\":\"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d'experts de l'IUFRO - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Bandeau-general.jpg\",\"datePublished\":\"2022-03-09T08:13:12+00:00\",\"dateModified\":\"2023-08-25T09:36:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Bandeau-general.jpg\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Bandeau-general.jpg\",\"width\":1800,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/pine-wood-nematode-december-iufro-expert-groups-conclusion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d&rsquo;experts de l&rsquo;IUFRO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"description\":\"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\",\"name\":\"comm IEFC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"caption\":\"comm IEFC\"},\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/author\\\/communication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d'experts de l'IUFRO  - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/","og_locale":"fr_FR","og_type":"article","og_title":"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d'experts de l'IUFRO  - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","og_url":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/","og_site_name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","article_published_time":"2022-03-09T08:13:12+00:00","article_modified_time":"2023-08-25T09:36:18+00:00","og_image":[{"width":1800,"height":300,"url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general.jpg","type":"image\/jpeg"}],"author":"comm IEFC","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"\u00c9crit par":"comm IEFC","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/"},"author":{"name":"comm IEFC","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a"},"headline":"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d&rsquo;experts de l&rsquo;IUFRO","datePublished":"2022-03-09T08:13:12+00:00","dateModified":"2023-08-25T09:36:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/"},"wordCount":2535,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general.jpg","articleSection":["Biotic","Risk management"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/","url":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/","name":"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d'experts de l'IUFRO - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/#primaryimage"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general.jpg","datePublished":"2022-03-09T08:13:12+00:00","dateModified":"2023-08-25T09:36:18+00:00","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/#primaryimage","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general.jpg","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/03\/Bandeau-general.jpg","width":1800,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/fr\/pine-wood-nematode-december-iufro-expert-groups-conclusion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/fr\/"},{"@type":"ListItem","position":2,"name":"N\u00e9matode du pin : conclusion de la r\u00e9union de d\u00e9cembre des groupes d&rsquo;experts de l&rsquo;IUFRO"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","description":"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a","name":"comm IEFC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","caption":"comm IEFC"},"url":"https:\/\/www.plantedforests.org\/fr\/author\/communication\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/5780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/comments?post=5780"}],"version-history":[{"count":10,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/5780\/revisions"}],"predecessor-version":[{"id":5860,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/5780\/revisions\/5860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/media\/5781"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/media?parent=5780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/categories?post=5780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/tags?post=5780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}