
{"id":2603,"date":"2008-01-19T09:33:26","date_gmt":"2008-01-19T08:33:26","guid":{"rendered":"https:\/\/www.iefc.net\/?p=2603"},"modified":"2023-08-25T11:37:44","modified_gmt":"2023-08-25T09:37:44","slug":"forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/fr\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/","title":{"rendered":"\u00ab\u00a0For\u00eats, leurs produits et services\u00a0\u00bb, Bordeaux 10, 11 et 12 mars 2008 &#8211; R\u00e9union annuelle du domaine COST"},"content":{"rendered":"<p class=\"corps_article\">Le domaine COST sur la for\u00eat est un des plus actifs des 9 domaines scientifiques, avec plus de 30 actions en cours. Le comit\u00e9 directeur et les coordinateurs des diff\u00e9rentes actions, des repr\u00e9sentants de la communaut\u00e9 scientifique et des orateurs invit\u00e9s se r\u00e9unissent \u00e0 Bordeaux du 10 au 12 Mars pour faire le point sur les actions en cours et discuter des futures en pr\u00e9paration. INRA et FCBA co-organisent cette r\u00e9union avec COST au conseil r\u00e9gional d&rsquo;Aquitaine o\u00f9 vous \u00eatres bienvenus pour les session publiques du 10 et 11 Mars. Pour les inscriptions contacter <a href=\"https:\/\/www.plantedforests.org\/message.php?destinataire=secretariat\">Claudia antoniotti<\/a>)<\/p>\n<p class=\"corps_article\">Nous vous encourageons \u00e0 soumettre de nouvelles actions COST avant le 28 Mars 2008.<br \/>\nLes propositions de jeunes chercheurs sont particuli\u00e8rement bienvenues.<br \/>\nUn pr\u00e9proposition doit couvrir un domaine et impliquer 5 pays au moins.plus d&rsquo;infos sur <a href=\"http:\/\/www.cost.esf.org\" target=\"_blank\" rel=\"noopener\">www.cost.esf.org<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le domaine COST sur la for\u00eat est un des plus actifs des 9 domaines scientifiques, avec plus de 30 actions en cours. Le comit\u00e9 directeur et les coordinateurs des diff\u00e9rentes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2603","post","type-post","status-publish","format-standard","hentry","category-archives"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"fr","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;For\u00eats, leurs produits et services&quot;, Bordeaux 10, 11 et 12 mars 2008 - R\u00e9union annuelle du domaine COST - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;For\u00eats, leurs produits et services&quot;, Bordeaux 10, 11 et 12 mars 2008 - R\u00e9union annuelle du domaine COST - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/\" \/>\n<meta property=\"og:site_name\" content=\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2008-01-19T08:33:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:37:44+00:00\" \/>\n<meta name=\"author\" content=\"Christophe Orazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christophe Orazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\\\/\"},\"author\":{\"name\":\"Christophe Orazio\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b18e9ff19844f867cee76d11998f187\"},\"headline\":\"\u00ab\u00a0For\u00eats, leurs produits et services\u00a0\u00bb, Bordeaux 10, 11 et 12 mars 2008 &#8211; R\u00e9union annuelle du domaine COST\",\"datePublished\":\"2008-01-19T08:33:26+00:00\",\"dateModified\":\"2023-08-25T09:37:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\\\/\"},\"wordCount\":308,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"articleSection\":[\"Archives\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\\\/\",\"name\":\"\\\"For\u00eats, leurs produits et services\\\", Bordeaux 10, 11 et 12 mars 2008 - R\u00e9union annuelle du domaine COST - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"datePublished\":\"2008-01-19T08:33:26+00:00\",\"dateModified\":\"2023-08-25T09:37:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forests, their Products and Services (FPS)\u0094 Bordeaux 10, 11 and 12 March 2008 &#8211; Annual COST domain meeting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"description\":\"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b18e9ff19844f867cee76d11998f187\",\"name\":\"Christophe Orazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"caption\":\"Christophe Orazio\"},\"sameAs\":[\"http:\\\/\\\/christophe-orazio.alwaysdata.net\\\/page_perso\\\/curriculum-vitae-cv\\\/\"],\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/author\\\/c-orazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"For\u00eats, leurs produits et services\", Bordeaux 10, 11 et 12 mars 2008 - R\u00e9union annuelle du domaine COST - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/","og_locale":"fr_FR","og_type":"article","og_title":"\"For\u00eats, leurs produits et services\", Bordeaux 10, 11 et 12 mars 2008 - R\u00e9union annuelle du domaine COST - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","og_url":"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/","og_site_name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","article_published_time":"2008-01-19T08:33:26+00:00","article_modified_time":"2023-08-25T09:37:44+00:00","author":"Christophe Orazio","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"\u00c9crit par":"Christophe Orazio","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/"},"author":{"name":"Christophe Orazio","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/6b18e9ff19844f867cee76d11998f187"},"headline":"\u00ab\u00a0For\u00eats, leurs produits et services\u00a0\u00bb, Bordeaux 10, 11 et 12 mars 2008 &#8211; R\u00e9union annuelle du domaine COST","datePublished":"2008-01-19T08:33:26+00:00","dateModified":"2023-08-25T09:37:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/"},"wordCount":308,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"articleSection":["Archives"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/","url":"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/","name":"\"For\u00eats, leurs produits et services\", Bordeaux 10, 11 et 12 mars 2008 - R\u00e9union annuelle du domaine COST - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"datePublished":"2008-01-19T08:33:26+00:00","dateModified":"2023-08-25T09:37:44+00:00","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/forets-leurs-produits-et-services-bordeaux-10-11-et-12-mars-2008-reunion-annuelle-du-domaine-cost\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Forests, their Products and Services (FPS)\u0094 Bordeaux 10, 11 and 12 March 2008 &#8211; Annual COST domain meeting"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","description":"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/6b18e9ff19844f867cee76d11998f187","name":"Christophe Orazio","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","caption":"Christophe Orazio"},"sameAs":["http:\/\/christophe-orazio.alwaysdata.net\/page_perso\/curriculum-vitae-cv\/"],"url":"https:\/\/www.plantedforests.org\/fr\/author\/c-orazio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/2603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/comments?post=2603"}],"version-history":[{"count":2,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/2603\/revisions"}],"predecessor-version":[{"id":2605,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/2603\/revisions\/2605"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/media?parent=2603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/categories?post=2603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/tags?post=2603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}