
{"id":2588,"date":"2007-07-03T22:53:51","date_gmt":"2007-07-03T20:53:51","guid":{"rendered":"https:\/\/www.iefc.net\/?p=2588"},"modified":"2023-08-25T11:38:23","modified_gmt":"2023-08-25T09:38:23","slug":"projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/fr\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/","title":{"rendered":"Projet Interreg DEFOR : Des innovations pour la r\u00e9colte du bois dans les Pyr\u00e9n\u00e9es"},"content":{"rendered":"<p>Le projet DEFOR a pour objectif l&rsquo;innovation et le transfert de technologies aux petites et moyennes entreprises foresti\u00e8res \u00e0 tous les niveaux de la cha\u00eene de production.<br \/>\nL&rsquo;action 1.4 de ce projet concerne la probl\u00e9matique de la r\u00e9colte du bois en zone de montagne, dont la ressource est aujourd&rsquo;hui sous-exploit\u00e9e. L&rsquo;objectif de cette action est de trouver des solutions innovantes pour pallier aux difficult\u00e9s techniques de l&rsquo;exploitation du bois en montagne, de fa\u00e7on \u00e0 accro\u00eetre la rentabilit\u00e9 et \u00e0 terme de d\u00e9velopper cette activit\u00e9.<\/p>\n<p>L&rsquo;Institut technologique FCBA, en charge de cette mission, s&rsquo;est concentr\u00e9 sur le contexte particulier de la cha\u00eene pyr\u00e9n\u00e9enne. Les techniques actuellement utilis\u00e9es par les professionnels de la r\u00e9gion ont \u00e9t\u00e9 inventori\u00e9es, et une \u00e9tude a \u00e9t\u00e9 men\u00e9e sur les techniques existant chez nos voisins europ\u00e9ens (Cf. \u00e9tudes ci-dessous). Plusieurs d&rsquo;entre elles ont \u00e9t\u00e9 s\u00e9lectionn\u00e9es et sont actuellement test\u00e9es.<\/p>\n<p class=\"vert\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.plantedforests.org\/old_resources\/DEFOR\/IMG_2235.JPG\" alt=\"D\u00e9bardage par c\u00e2ble m\u00e2t\" width=\"250\" height=\"300\" align=\"right\" border=\"0\" hspace=\"20\" vspace=\"30\" \/>Etude 1 : Le parc des engins forestiers sur la cha\u00eene pyr\u00e9n\u00e9enne fran\u00e7aise<\/p>\n<p>La description du parc des mat\u00e9riels utilis\u00e9s pour la r\u00e9colte des bois offre une bonne image des syst\u00e8mes d&rsquo;exploitation utilis\u00e9s. Sur l&rsquo;ensemble des d\u00e9partements de la cha\u00eene pyr\u00e9n\u00e9enne, un recensement montre une tr\u00e8s forte domination des d\u00e9busqueurs puisqu&rsquo;ils repr\u00e9sentent plus de 71% des mat\u00e9riels de b\u00fbcheronnage et de d\u00e9bardage. Ces engins tr\u00e8s robustes \u0096 la moyenne d&rsquo;\u00e2ge est de 14 ans \u0096 permettent de mobiliser la ressource \u00e0 proximit\u00e9 des pistes et des tra\u00eenes, ces derni\u00e8res \u00e9tant implant\u00e9es aux frais de l&rsquo;acheteur des bois sur pied. La m\u00e9canisation du b\u00fbcheronnage et le d\u00e9bardage par c\u00e2ble a\u00e9rien n&rsquo;ont pas encore trouv\u00e9 leur place dans les Pyr\u00e9n\u00e9es. Seules deux \u00e9quipes fran\u00e7aises pratiquent le d\u00e9bardage par c\u00e2ble sur les 6 d\u00e9partements enqu\u00eat\u00e9s. Les besoins en renouvellement sont estim\u00e9s \u00e0 une cinquantaine de mat\u00e9riels sur la p\u00e9riode 2007-2013 correspondant \u00e0 la dur\u00e9e du Contrat de Projet en cours.<\/p>\n<p class=\"vert\">Etude 2 : Exploitation en montagne fran\u00e7aise : \u00e9volutions r\u00e9centes des techniques de d\u00e9bardage<\/p>\n<p>Les for\u00eats de montagne rec\u00e8lent 30% de la ressource foresti\u00e8re en France. Les r\u00e9coltes sont en diminution dans les massifs des Alpes et des Pyr\u00e9n\u00e9es et il est indispensable de promouvoir de nouvelles techniques de r\u00e9colte. L&rsquo;article fait le point sur quelques \u00e9volutions technologiques venant de l&rsquo;\u00e9tranger. C&rsquo;est surtout dans le domaine du d\u00e9bardage par c\u00e2ble t\u00e9l\u00e9ph\u00e9rique que les \u00e9volutions sont les plus importantes avec l&rsquo;utilisation accrue de l&rsquo;\u00e9lectronique et l&rsquo;int\u00e9gration d&rsquo;un \u00e9quipement de b\u00fbcheronnage m\u00e9canis\u00e9 au pied du c\u00e2ble-m\u00e2t sur la plate-forme d&rsquo;un camion porte-outil. Ces derni\u00e8res \u00e9volutions devraient contribuer \u00e0 accro\u00eetre la comp\u00e9titivit\u00e9 de ce mode de d\u00e9bardage qui concilie la possibilit\u00e9 d&rsquo;acc\u00e9der \u00e0 de nouvelles ressources \u00e0 des avantages environnementaux tr\u00e8s appr\u00e9ci\u00e9s des gestionnaires forestiers. <a href=\"http:\/\/www.afocel.fr\/Publications\/FIF\/FIF754.pdf\"> Lire l&rsquo;article complet<\/a><\/p>\n<p class=\"T1\">\nExp\u00e9rimentation de nouvelles techniques : les premiers r\u00e9sultats<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.plantedforests.org\/old_resources\/DEFOR\/IMG_2277.JPG\" alt=\"D\u00e9bardage par c\u00e2ble m\u00e2t\" width=\"300\" height=\"200\" align=\"left\" border=\"0\" hspace=\"20\" \/> Deux journ\u00e9es de d\u00e9monstration ont eu lieu les 27 et 28 novembre 2007 dans les Pyr\u00e9n\u00e9es Orientales et les Pyr\u00e9n\u00e9es Atlantiques. Elles ont permis de pr\u00e9senter des techniques prometteuses, dont l&rsquo;une en particulier a imm\u00e9diatement conquis les professionnels de l&rsquo;exploitation foresti\u00e8re pr\u00e9sents sur le site. Il s&rsquo;agit du <b>d\u00e9bardage \u00e0 l&rsquo;aide d&rsquo;un c\u00e2ble textile synth\u00e9tique install\u00e9 sur un d\u00e9busqueur<\/b> : ce c\u00e2ble \u00e0 la fois solide et l\u00e9ger a prouv\u00e9 son efficacit\u00e9 et montr\u00e9 des avantages certains en terme de rapidit\u00e9, s\u00e9curit\u00e9 et praticit\u00e9 d&rsquo;utilisation. <a href=\"https:\/\/www.plantedforests.org\/old_resources\/DEFOR\/Pres28nov_FR.pdf\"> Informations techniques<\/a><br \/>\nLa deuxi\u00e8me visite pr\u00e9sentait un chantier de d\u00e9bardage par c\u00e2ble-m\u00e2t, m\u00e9thode encore peu r\u00e9pandue dans la cha\u00eene pyr\u00e9n\u00e9enne.<br \/>\nCes visites, ouvertes \u00e0 tous, se sont en outre d\u00e9roul\u00e9es dans d&rsquo;excellentes conditions et ont permis des \u00e9changes constructifs entre les partenaires et visiteurs espagnols, fran\u00e7ais et portugais dans une atmosph\u00e8re conviviale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le projet DEFOR a pour objectif l&rsquo;innovation et le transfert de technologies aux petites et moyennes entreprises foresti\u00e8res \u00e0 tous les niveaux de la cha\u00eene de production. L&rsquo;action 1.4 de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2588","post","type-post","status-publish","format-standard","hentry","category-archives"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"fr","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projet Interreg DEFOR : Des innovations pour la r\u00e9colte du bois dans les Pyr\u00e9n\u00e9es - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projet Interreg DEFOR : Des innovations pour la r\u00e9colte du bois dans les Pyr\u00e9n\u00e9es - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/\" \/>\n<meta property=\"og:site_name\" content=\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2007-07-03T20:53:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plantedforests.org\/old_resources\/DEFOR\/IMG_2235.JPG\" \/>\n<meta name=\"author\" content=\"Christophe Orazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christophe Orazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/\"},\"author\":{\"name\":\"Christophe Orazio\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b18e9ff19844f867cee76d11998f187\"},\"headline\":\"Projet Interreg DEFOR : Des innovations pour la r\u00e9colte du bois dans les Pyr\u00e9n\u00e9es\",\"datePublished\":\"2007-07-03T20:53:51+00:00\",\"dateModified\":\"2023-08-25T09:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/\"},\"wordCount\":1210,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/old_resources\\\/DEFOR\\\/IMG_2235.JPG\",\"articleSection\":[\"Archives\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/\",\"name\":\"Projet Interreg DEFOR : Des innovations pour la r\u00e9colte du bois dans les Pyr\u00e9n\u00e9es - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/old_resources\\\/DEFOR\\\/IMG_2235.JPG\",\"datePublished\":\"2007-07-03T20:53:51+00:00\",\"dateModified\":\"2023-08-25T09:38:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/old_resources\\\/DEFOR\\\/IMG_2235.JPG\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/old_resources\\\/DEFOR\\\/IMG_2235.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interreg Project DEFOR : Innovation for wood extraction in the Pyrenean chain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"description\":\"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b18e9ff19844f867cee76d11998f187\",\"name\":\"Christophe Orazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"caption\":\"Christophe Orazio\"},\"sameAs\":[\"http:\\\/\\\/christophe-orazio.alwaysdata.net\\\/page_perso\\\/curriculum-vitae-cv\\\/\"],\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/author\\\/c-orazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projet Interreg DEFOR : Des innovations pour la r\u00e9colte du bois dans les Pyr\u00e9n\u00e9es - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/","og_locale":"fr_FR","og_type":"article","og_title":"Projet Interreg DEFOR : Des innovations pour la r\u00e9colte du bois dans les Pyr\u00e9n\u00e9es - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","og_url":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/","og_site_name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","article_published_time":"2007-07-03T20:53:51+00:00","article_modified_time":"2023-08-25T09:38:23+00:00","og_image":[{"url":"https:\/\/www.plantedforests.org\/old_resources\/DEFOR\/IMG_2235.JPG","type":"","width":"","height":""}],"author":"Christophe Orazio","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"\u00c9crit par":"Christophe Orazio","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/"},"author":{"name":"Christophe Orazio","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/6b18e9ff19844f867cee76d11998f187"},"headline":"Projet Interreg DEFOR : Des innovations pour la r\u00e9colte du bois dans les Pyr\u00e9n\u00e9es","datePublished":"2007-07-03T20:53:51+00:00","dateModified":"2023-08-25T09:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/"},"wordCount":1210,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"image":{"@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/old_resources\/DEFOR\/IMG_2235.JPG","articleSection":["Archives"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/","url":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/","name":"Projet Interreg DEFOR : Des innovations pour la r\u00e9colte du bois dans les Pyr\u00e9n\u00e9es - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/#primaryimage"},"image":{"@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/old_resources\/DEFOR\/IMG_2235.JPG","datePublished":"2007-07-03T20:53:51+00:00","dateModified":"2023-08-25T09:38:23+00:00","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/#primaryimage","url":"https:\/\/www.plantedforests.org\/old_resources\/DEFOR\/IMG_2235.JPG","contentUrl":"https:\/\/www.plantedforests.org\/old_resources\/DEFOR\/IMG_2235.JPG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/projet-interreg-defor-des-innovations-pour-la-recolte-du-bois-dans-les-pyrenees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Interreg Project DEFOR : Innovation for wood extraction in the Pyrenean chain"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","description":"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/6b18e9ff19844f867cee76d11998f187","name":"Christophe Orazio","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","caption":"Christophe Orazio"},"sameAs":["http:\/\/christophe-orazio.alwaysdata.net\/page_perso\/curriculum-vitae-cv\/"],"url":"https:\/\/www.plantedforests.org\/fr\/author\/c-orazio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/2588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/comments?post=2588"}],"version-history":[{"count":2,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/2588\/revisions"}],"predecessor-version":[{"id":2590,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/2588\/revisions\/2590"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/media?parent=2588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/categories?post=2588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/tags?post=2588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}