
{"id":2570,"date":"2007-01-20T16:39:55","date_gmt":"2007-01-20T15:39:55","guid":{"rendered":"https:\/\/www.iefc.net\/?p=2570"},"modified":"2023-08-25T11:38:23","modified_gmt":"2023-08-25T09:38:23","slug":"une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/fr\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/","title":{"rendered":"Une plan\u00e8te de forestiers : quand planter des millions d&rsquo;arbres devient tendance"},"content":{"rendered":"<p class=\"corps_article\">Alors que chaque salari\u00e9 des entreprises de travaux forestiers plante des milliers d&rsquo;arbres par jour de depuis des dizaines d&rsquo;ann\u00e9es, que depuis des centaines d&rsquo;ann\u00e9es, les forestiers \u00e9tudient les modes de r\u00e9g\u00e9n\u00e9ration les plus adapt\u00e9s, les milieux qui conviennent le mieux selon les esp\u00e8ces d&rsquo;arbres, accompagnent la croissance et la gestion de leurs peuplements forestiers, sans en faire \u00e9tat \u00e0 la soci\u00e9t\u00e9, de plus en plus de fondations et de grandes marques d\u00e9couvrent que les arbres existent!<\/p>\n<p class=\"corps_article\">Les projets \u00ab\u00a0plantons des milliers d&rsquo;arbres\u00a0\u00bb explosent actuelllement, sans qu&rsquo;on ait toujours des garanties sur les comp\u00e9tences des gens qui effectuent ces plantations, ni sur le suivi qui va \u00eatre fait des ces peuplements. Le pass\u00e9 montre que des reboisements massifs comme au magreb ou au sahara par des gens sans comp\u00e9tences techniques aboutissent \u00e0 la mort de tous les plants, et que g\u00e9n\u00e9ralement les professionnels doivent replanter tous les arbres mis en terre par les <a href=\"http:\/\/www.ambafrance-ke.org\/article.php3?id_article=721\">\u00e9coles<\/a>!<br \/>\nCependant, on peut supposer que des institutions telles que l&rsquo;agence des nations unies <a href=\"http:\/\/www.unep.org\/billiontreecampaign\/\">UNEP<\/a> ou des <a href=\"http:\/\/www.masarboles.es\/congresos\/index.php?b=1&amp;c=1\">fondations adoss\u00e9es \u00e0 des professionnels<\/a> puissent g\u00e9n\u00e9rer des plantations qui vont durer.<\/p>\n<p class=\"corps_article\">Le risque c&rsquo;est qu&rsquo;il devient vite tr\u00e8s tendance de promouvoir la plantation des arbres, qu&rsquo;on soit un <a href=\"http:\/\/www.20minutos.es\/noticia\/216544\/0\/sebastian\/promete\/gallardon\/\">homme politique en campagne<\/a>, une<a href=\"http:\/\/www.ecumenico.org\/leer.php\/166\"> fondation d&rsquo;opposition \u00e0 un r\u00e9gime paramilitaire<\/a> , <a href=\"http:\/\/www.obrasocialcajamadrid.es\/ObraSocial\/os_cruce\/0,0,70118_1305416_0_0,00.html\">une banque<\/a>, ou une<a href=\"http:\/\/www.yves-rocher.com\/fr\/plantons\/\">marque de cosm\u00e9tique c\u00e9l\u00e8bre<\/a>. (Les moteurs de recherche peuvent vous donner de nombreux autres exemples)<\/p>\n<p class=\"corps_article\">La foresterie qui est un acte qui engage sur plusieurs ann\u00e9es, voire plusieurs dizaines d&rsquo;ann\u00e9es s&rsquo;accomode mal de ces ph\u00e9no\u00e8nes de modes. M\u00eame si on ne peut que se r\u00e9jouir de l&rsquo;int\u00e9r\u00eat grandissant du public pour notre m\u00e9tier, on peut s&rsquo;int\u00e9rroger sur les risques d&rsquo;amalgames et les raccourcis faits par les diff\u00e9rentes fondations, par exemple ne pas laisser croire que la d\u00e9forestation a lieu en europe o\u00f9 la superficie foresti\u00e8re augmente r\u00e9guli\u00e8rement depuis 60 ans, ne pas trop promouvoir l&rsquo;utilisation du bois exotique non g\u00e9r\u00e9 durablement ou du plastique PVC en faisant croire que tous les fabricants de fen\u00e8tres bois font disparaitre la for\u00eat! Il faut rappler aussi que face \u00e0 tous ces soncurents, le mat\u00e9riau bois et le seul \u00e0 \u00eatre renouvelable et biod\u00e9gradable, que se soit pour faire du feu, des constructions, des emballages ou des meubles!<\/p>\n<p class=\"corps_article\">En r\u00e9sum\u00e9, c&rsquo;est bien que la soci\u00e9t\u00e9, les fondations et les communicants s&rsquo;int\u00e9ressent aux arbres, mais il faudra certainement rapidement se poser la question de comment les partenaires professionnels s&rsquo;associent \u00e0 cette dynamique, pour \u00e9viter les raccourcis dramatiques et pour que le r\u00e9sultat soit positif pour tous!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que chaque salari\u00e9 des entreprises de travaux forestiers plante des milliers d&rsquo;arbres par jour de depuis des dizaines d&rsquo;ann\u00e9es, que depuis des centaines d&rsquo;ann\u00e9es, les forestiers \u00e9tudient les modes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2570","post","type-post","status-publish","format-standard","hentry","category-archives"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"fr","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":false,"content":false,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une plan\u00e8te de forestiers : quand planter des millions d&#039;arbres devient tendance - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une plan\u00e8te de forestiers : quand planter des millions d&#039;arbres devient tendance - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/\" \/>\n<meta property=\"og:site_name\" content=\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2007-01-20T15:39:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:38:23+00:00\" \/>\n<meta name=\"author\" content=\"Christophe Orazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christophe Orazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\\\/\"},\"author\":{\"name\":\"Christophe Orazio\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b18e9ff19844f867cee76d11998f187\"},\"headline\":\"Une plan\u00e8te de forestiers : quand planter des millions d&rsquo;arbres devient tendance\",\"datePublished\":\"2007-01-20T15:39:55+00:00\",\"dateModified\":\"2023-08-25T09:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\\\/\"},\"wordCount\":977,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"articleSection\":[\"Archives\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\\\/\",\"name\":\"Une plan\u00e8te de forestiers : quand planter des millions d'arbres devient tendance - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"datePublished\":\"2007-01-20T15:39:55+00:00\",\"dateModified\":\"2023-08-25T09:38:23+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"description\":\"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b18e9ff19844f867cee76d11998f187\",\"name\":\"Christophe Orazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"caption\":\"Christophe Orazio\"},\"sameAs\":[\"http:\\\/\\\/christophe-orazio.alwaysdata.net\\\/page_perso\\\/curriculum-vitae-cv\\\/\"],\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/author\\\/c-orazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une plan\u00e8te de forestiers : quand planter des millions d'arbres devient tendance - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/","og_locale":"fr_FR","og_type":"article","og_title":"Une plan\u00e8te de forestiers : quand planter des millions d'arbres devient tendance - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","og_url":"https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/","og_site_name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","article_published_time":"2007-01-20T15:39:55+00:00","article_modified_time":"2023-08-25T09:38:23+00:00","author":"Christophe Orazio","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"\u00c9crit par":"Christophe Orazio","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/"},"author":{"name":"Christophe Orazio","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/6b18e9ff19844f867cee76d11998f187"},"headline":"Une plan\u00e8te de forestiers : quand planter des millions d&rsquo;arbres devient tendance","datePublished":"2007-01-20T15:39:55+00:00","dateModified":"2023-08-25T09:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/"},"wordCount":977,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"articleSection":["Archives"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/","url":"https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/","name":"Une plan\u00e8te de forestiers : quand planter des millions d'arbres devient tendance - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"datePublished":"2007-01-20T15:39:55+00:00","dateModified":"2023-08-25T09:38:23+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/pt\/une-planete-de-forestiers-quand-planter-des-millions-darbres-devient-tendance\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","description":"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/6b18e9ff19844f867cee76d11998f187","name":"Christophe Orazio","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","caption":"Christophe Orazio"},"sameAs":["http:\/\/christophe-orazio.alwaysdata.net\/page_perso\/curriculum-vitae-cv\/"],"url":"https:\/\/www.plantedforests.org\/fr\/author\/c-orazio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/2570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/comments?post=2570"}],"version-history":[{"count":2,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/2570\/revisions"}],"predecessor-version":[{"id":2572,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/2570\/revisions\/2572"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/media?parent=2570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/categories?post=2570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/tags?post=2570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}