
{"id":11586,"date":"2023-04-21T09:30:20","date_gmt":"2023-04-21T07:30:20","guid":{"rendered":"https:\/\/www.plantedforests.org\/?p=11586"},"modified":"2023-08-25T11:35:37","modified_gmt":"2023-08-25T09:35:37","slug":"managing-mixtures-vs-monocultures-what-do-we-know","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/","title":{"rendered":"Gestion des m\u00e9langes vs. monocultures : que savons-nous ?"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong><u><strong><u>Faits relatifs \u00e0 la r\u00e9union <\/u><\/strong>:<\/u><\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">&#8211; <strong>Titre, date et lieu de la r\u00e9union :<\/strong> \u00ab\u00a0Gestion des for\u00eats plant\u00e9es mixtes et pures : Stock-taking of science and practice\u00a0\u00bb, 29 et 30 septembre 2022, si\u00e8ge de la FAO, Rome (Italie)<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">&#8211; <strong>Unit\u00e9 de l&rsquo;IUFRO impliqu\u00e9e et organisations sponsors :<\/strong> Taskforce IUFRO \u00ab\u00a0Resilient planted forests serving society &amp; bioeconomy\u00a0\u00bb, atelier organis\u00e9 par la Food and Agriculture Organization (FAO), le r\u00e9seau TreeDivNet, et la Commission internationale sur les peupliers et autres arbres \u00e0 croissance rapide qui soutiennent les populations et l&rsquo;environnement (IPC).<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">&#8211; <strong>Nombre de participants : 35<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">&#8211; <strong>Pays repr\u00e9sent\u00e9s :<\/strong> participants venant de 14 pays (Allemagne, Argentine, Australie, Belgique, Br\u00e9sil, \u00c9tats-Unis, France, Italie, Madagascar, Pologne, Portugal, Su\u00e8de, Suisse, Ouganda) pour assister \u00e0 l&rsquo;\u00e9v\u00e9nement en pr\u00e9sentiel. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image4-1024x683.jpg\" alt=\"\" class=\"wp-image-11585\" srcset=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image4-1024x683.jpg 1024w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image4-300x200.jpg 300w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image4-150x100.jpg 150w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image4-768x512.jpg 768w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image4.jpg 1100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Credits: FAO<\/figcaption><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong><u>Contenus :<\/u><\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Des for\u00eats plant\u00e9es plus diversifi\u00e9es peuvent r\u00e9pondre \u00e0 des objectifs soci\u00e9taux plus larges en am\u00e9liorant la r\u00e9silience et les services \u00e9cosyst\u00e9miques par rapport aux plantations en monoculture. Cependant, il y a souvent un manque d&rsquo;information, d&rsquo;exp\u00e9rience et de mat\u00e9riel g\u00e9n\u00e9tique n\u00e9cessaire pour mettre en \u0153uvre des for\u00eats plant\u00e9es d&rsquo;esp\u00e8ces mixtes \u00e0 grande \u00e9chelle.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Pour combler cette lacune, la <a href=\"https:\/\/www.fao.org\/home\/en\/\"><strong>FAO<u>[1]<\/u><\/strong><\/a><strong>, le r\u00e9seau <\/strong><a href=\"https:\/\/treedivnet.ugent.be\/index.html\"><strong>TreeDivNet<\/strong><\/a>, et l\u2019<a href=\"https:\/\/www.fao.org\/ipc\/en\/\"><strong>IPC<u>[2]<\/u><\/strong><\/a> ont organis\u00e9 un atelier visant \u00e0 faire le point sur la gestion des for\u00eats plant\u00e9es mixtes et pures. L&rsquo;atelier a contribu\u00e9 aux projets <a href=\"https:\/\/www.cambio-treediversity.com\/\">Cambio<\/a> et <a href=\"https:\/\/treedivnet.ugent.be\/ProjectMixForChange.html\">MixForChange<\/a>, et a \u00e9t\u00e9 envisag\u00e9 dans le cadre du groupe de travail de l\u2019IUFRO TaskForce <a href=\"https:\/\/www.iufro.org\/science\/task-forces\/resilient-planted-forests\/\">\u201cResilient planted forests serving society &amp; bioeconomy\u201d<\/a>. L&rsquo;atelier a rassembl\u00e9 35 participants du monde entier au si\u00e8ge de la FAO, \u00e0 Rome, en Italie, et comprenait une table ronde r\u00e9unissant des repr\u00e9sentants de l&rsquo;Argentine, de l&rsquo;Italie, de Madagascar, de l&rsquo;Ouganda et des \u00c9tats-Unis d&rsquo;Am\u00e9rique.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Selon <a href=\"https:\/\/www.fao.org\/3\/ca9825en\/ca9825en.pdf\">l&rsquo;\u00e9valuation des ressources foresti\u00e8res mondiales de la FAO<\/a>, la superficie des for\u00eats plant\u00e9es a augment\u00e9 de 72 % depuis 1990, passant de 170 millions d&rsquo;hectares \u00e0 293 millions d&rsquo;hectares en 2020. Le bois \u00e9tant reconnu comme un mat\u00e9riau pouvant contribuer aux objectifs environnementaux et socio-\u00e9conomiques des nations unis, la demande de bois durable est susceptible d&rsquo;augmenter et d&rsquo;\u00eatre satisfaite par les for\u00eats plant\u00e9es. La n\u00e9cessit\u00e9 urgente de restaurer les terres d\u00e9grad\u00e9es \u00e0 l&rsquo;\u00e9chelle mondiale exige \u00e9galement que l&rsquo;on prenne en consid\u00e9ration le r\u00f4le des for\u00eats plant\u00e9es.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Les exp\u00e9riences de plantations en m\u00e9lange effectu\u00e9es par TreeDivNet autour de la plan\u00e8te fournissent des preuves scientifiques de l&rsquo;augmentation de la r\u00e9silience et de la fourniture de services \u00e9cosyst\u00e9miques par les for\u00eats plant\u00e9es en m\u00e9lange par rapport aux for\u00eats monosp\u00e9cifiques. L&rsquo;augmentation de la richesse en esp\u00e8ces d&rsquo;arbres est associ\u00e9e \u00e0 une augmentation de la multifonctionnalit\u00e9, de la biodiversit\u00e9 et de la productivit\u00e9 relative. Les m\u00e9langes sont \u00e9galement importants pour r\u00e9partir les risques, ce qui est d&rsquo;autant plus pertinent que le changement climatique est susceptible d&rsquo;accro\u00eetre consid\u00e9rablement les menaces abiotiques et biotiques qui p\u00e8sent sur les for\u00eats plant\u00e9es.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image3-1024x684.jpg\" alt=\"\" class=\"wp-image-11584\" srcset=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image3-1024x684.jpg 1024w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image3-300x200.jpg 300w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image3-150x100.jpg 150w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image3-768x513.jpg 768w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image3.jpg 1113w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Credits: FAO<\/figcaption><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">La demande croissante de mat\u00e9riaux renouvelables et de solutions naturelles pour r\u00e9pondre aux d\u00e9fis du changement climatique pr\u00e9sente \u00e0 la fois des opportunit\u00e9s et des risques pour les investissements forestiers. Des for\u00eats plant\u00e9es plus diversifi\u00e9es peuvent offrir aux propri\u00e9taires fonciers, y compris aux petits exploitants, des options int\u00e9ressantes pour investir dans la sylviculture de mani\u00e8re plus sure. Le potentiel des for\u00eats plant\u00e9es plus mixtes augmente avec l&rsquo;importance croissante des services \u00e9cosyst\u00e9miques commercialisables autres que la production de bois.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Toutefois, la mise en \u0153uvre \u00e0 grande \u00e9chelle de diverses for\u00eats plant\u00e9es n\u00e9cessite des lignes directrices simples et pratiques pour surmonter la complexit\u00e9 op\u00e9rationnelle. Il existe un d\u00e9calage important entre la disponibilit\u00e9 des r\u00e9sultats de la recherche et leur adoption par les producteurs ruraux, en particulier dans les petites et moyennes propri\u00e9t\u00e9s. Pour permettre l&rsquo;expansion des plantations mixtes, celles-ci doivent \u00eatre per\u00e7ues comme techniquement solides, \u00e9conomiquement viables et socialement acceptables.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Les participants ont convenu d&rsquo;une feuille de route visant \u00e0 lancer une publication conjointe en novembre 2023 lors du <a href=\"https:\/\/www.plantedforests.org\/icpf-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Congr\u00e8s International sur les For\u00eats Plant\u00e9es<\/a> (ICPF2023), afin de contribuer \u00e0 combler le foss\u00e9 entre la science et la pratique sur le sujet des for\u00eats plant\u00e9es d&rsquo;esp\u00e8ces mixtes.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><strong><strong>Acc\u00e9der au rapport complet de l&rsquo;atelier <\/strong><a href=\"https:\/\/www.iufro.org\/science\/task-forces\/resilient-planted-forests\/activities\/\"><strong>ici<\/strong><\/a><strong>.<\/strong><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> Food and Agriculture Organization of the United Nations<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref2\" id=\"_ftn2\">[2]<\/a> International Commission on Poplars and Other Fast-Growing Trees Sustaining People and the Environment<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faits relatifs \u00e0 la r\u00e9union : &#8211; Titre, date et lieu de la r\u00e9union : \u00ab\u00a0Gestion des for\u00eats plant\u00e9es mixtes et pures : Stock-taking of science and practice\u00a0\u00bb, 29 et [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":11547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"fr","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gestion des m\u00e9langes vs. monocultures : que savons-nous ? - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestion des m\u00e9langes vs. monocultures : que savons-nous ? - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/\" \/>\n<meta property=\"og:site_name\" content=\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-21T07:30:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:35:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1089\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comm IEFC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"comm IEFC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/\"},\"author\":{\"name\":\"comm IEFC\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\"},\"headline\":\"Gestion des m\u00e9langes vs. monocultures : que savons-nous ?\",\"datePublished\":\"2023-04-21T07:30:20+00:00\",\"dateModified\":\"2023-08-25T09:35:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/\"},\"wordCount\":2874,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Image2.jpg\",\"articleSection\":[\"Archives\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/\",\"name\":\"Gestion des m\u00e9langes vs. monocultures : que savons-nous ? - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Image2.jpg\",\"datePublished\":\"2023-04-21T07:30:20+00:00\",\"dateModified\":\"2023-08-25T09:35:37+00:00\",\"description\":\"Archives\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Image2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Image2.jpg\",\"width\":1089,\"height\":612},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/managing-mixtures-vs-monocultures-what-do-we-know\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gestion des m\u00e9langes vs. monocultures : que savons-nous ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC\",\"description\":\"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\",\"name\":\"comm IEFC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"caption\":\"comm IEFC\"},\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/author\\\/communication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gestion des m\u00e9langes vs. monocultures : que savons-nous ? - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/","og_locale":"fr_FR","og_type":"article","og_title":"Gestion des m\u00e9langes vs. monocultures : que savons-nous ? - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","og_url":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/","og_site_name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","article_published_time":"2023-04-21T07:30:20+00:00","article_modified_time":"2023-08-25T09:35:37+00:00","og_image":[{"width":1089,"height":612,"url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image2.jpg","type":"image\/jpeg"}],"author":"comm IEFC","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"\u00c9crit par":"comm IEFC","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/"},"author":{"name":"comm IEFC","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a"},"headline":"Gestion des m\u00e9langes vs. monocultures : que savons-nous ?","datePublished":"2023-04-21T07:30:20+00:00","dateModified":"2023-08-25T09:35:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/"},"wordCount":2874,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image2.jpg","articleSection":["Archives"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/","url":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/","name":"Gestion des m\u00e9langes vs. monocultures : que savons-nous ? - Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/#primaryimage"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image2.jpg","datePublished":"2023-04-21T07:30:20+00:00","dateModified":"2023-08-25T09:35:37+00:00","description":"Archives","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/#primaryimage","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image2.jpg","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/04\/Image2.jpg","width":1089,"height":612},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/fr\/managing-mixtures-vs-monocultures-what-do-we-know\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Gestion des m\u00e9langes vs. monocultures : que savons-nous ?"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - IEFC","description":"Le r\u00e9seau multi-acteur pour la gestion durable et la r\u00e9silience des for\u00eats cultiv\u00e9es","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a","name":"comm IEFC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","caption":"comm IEFC"},"url":"https:\/\/www.plantedforests.org\/fr\/author\/communication\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/11586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/comments?post=11586"}],"version-history":[{"count":24,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/11586\/revisions"}],"predecessor-version":[{"id":12281,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/posts\/11586\/revisions\/12281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/media\/11547"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/media?parent=11586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/categories?post=11586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/fr\/wp-json\/wp\/v2\/tags?post=11586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}