
{"id":5400,"date":"2021-12-03T09:24:57","date_gmt":"2021-12-03T08:24:57","guid":{"rendered":"https:\/\/www.iefc.net\/?p=5400"},"modified":"2023-08-25T11:36:32","modified_gmt":"2023-08-25T09:36:32","slug":"conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/es\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/","title":{"rendered":"Conferencia final de SustForest+: la resina tiene futuro"},"content":{"rendered":"\n<p>La extracci\u00f3n de resina est\u00e1 en auge y el proyecto SustForest+ le ha dado un impulso. La reuni\u00f3n de clausura de este proyecto europeo Interreg-Sudoe fue organizada por el Instituto Europeo del Bosque Cultivado y el Centro Regional de la Propiedad Forestal de Nueva Aquitania.<br>Conf\u00e9rence finale SustForest+ en novembre 2021<\/p>\n\n\n\n<p>Tuvo lugar los d\u00edas 9 y 10 de noviembre de 2021, en el Consejo Regional de Nueva Aquitania en Burdeos y luego en el INRAe en Cestas-Pierroton. Estos dos d\u00edas de intercambio de conocimientos fueron seguidos por una visita a la empresa Biolandes, que produce numerosos aceites esenciales y extractos arom\u00e1ticos naturales en Le Sen. En particular, Biolandes destila la resina recogida por la empresa Holiste para la producci\u00f3n de aceite esencial de pino utilizado en aromaterapia.<\/p>\n\n\n\n<p>La conferencia fue una oportunidad \u00fanica para que las personas interesadas en la explotaci\u00f3n del pino, en Francia, intercambiaran con los actores que vinieron a compartir sus experiencias desde Espa\u00f1a, Portugal y Brasil.<\/p>\n\n\n\n<p>Las condiciones del mercado internacional de la resina son muy favorables para el desarrollo de este sector en todo el mundo y la actividad vuelve a ser rentable en el sur de Europa (v\u00e9ase la nota de perspectivas). Las crecientes necesidades de resina de China no pueden satisfacerse \u00fanicamente con el aumento de la producci\u00f3n de resina brasile\u00f1a. La producci\u00f3n de tall oil, subproducto de la industria papelera, depende totalmente del desarrollo de esta industria y, por tanto, no puede sustituir a la producci\u00f3n de resina. Estas condiciones han provocado un aumento significativo del precio de este recurso en el mercado internacional. Si China no puede satisfacer sus necesidades de resina mediante la importaci\u00f3n de oleorresina, recurrir\u00e1 m\u00e1s a las resinas de hidrocarburos y aumentar\u00e1 su producci\u00f3n de productos derivados del petr\u00f3leo. La estrategia europea para la bioeconom\u00eda, que favorece el desarrollo de la qu\u00edmica de base biol\u00f3gica, tambi\u00e9n podr\u00eda promover el desarrollo del sector de la oleorresina, asegurando al mismo tiempo su suministro local de una materia prima muy vers\u00e1til.<\/p>\n\n\n\n<p>En este contexto econ\u00f3mico y social favorable se ha llevado a cabo la investigaci\u00f3n en el marco del proyecto europeo SustForest+. Durante la conferencia, Ricardo Alia (INIA) present\u00f3 un m\u00e9todo para cartografiar las zonas con alto potencial de producci\u00f3n de resina, que podr\u00eda permitir en el futuro la selecci\u00f3n de rodales de inter\u00e9s. La mejora gen\u00e9tica de rodales para la producci\u00f3n de oleorresina es tambi\u00e9n una de las v\u00edas exploradas por el INIA y por Ricardo Soares, que vino desde Brasil para presentar su experiencia en el campo de la mejora gen\u00e9tica. En este pa\u00eds, que es el principal exportador mundial, la mejora gen\u00e9tica ha permitido duplicar la productividad de resina por \u00e1rbol y aumentar considerablemente la rentabilidad de la actividad. Esta mejora es posible gracias a la variabilidad gen\u00e9tica en la producci\u00f3n de resina que existe de forma natural en los pinos. Posteriormente, Morandise Rubini, de la Universidad de Pau, demostr\u00f3 que era posible caracterizar qu\u00edmicamente la resina en funci\u00f3n de su origen geogr\u00e1fico, de la especie de pino y de la t\u00e9cnica de extracci\u00f3n de la resina. La resina de pino mar\u00edtimo de la regi\u00f3n de las Landas presenta propiedades interesantes, con una alta concentraci\u00f3n de alfa-pineno y un alto contenido en trementina, ligado al m\u00e9todo de recolecci\u00f3n. Dado que el desarrollo de la explotaci\u00f3n del pino no puede hacerse en detrimento de la producci\u00f3n de madera, Marl\u00e8ne Baudet (CNPF) present\u00f3 un estudio realizado en colaboraci\u00f3n con Jean-Denis Lanvin (FCBA), destinado a mostrar los efectos de la extracci\u00f3n de resina sobre la calidad de la madera. El estudio demuestra que la extracci\u00f3n de resina no altera las prestaciones mec\u00e1nicas de la madera y que, por el contrario, podr\u00eda mejorarlas (m\u00e1s informaci\u00f3n sobre el estudio).<\/p>\n\n\n\n<p>La conferencia fue tambi\u00e9n una oportunidad para presentar la Red Europea de Territorios Resineros creada por los miembros del proyecto SustForest+, que garantizar\u00e1 la cooperaci\u00f3n internacional en este tema tras el proyecto. En Francia, forman parte de esta red el IEFC y el CRPF como miembros fundadores y la asociaci\u00f3n Gemme la For\u00eat d&#8217;Aquitaine representada por Cyrille Fournet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La extracci\u00f3n de resina est\u00e1 en auge y el proyecto SustForest+ le ha dado un impulso. La reuni\u00f3n de clausura de este proyecto europeo Interreg-Sudoe fue organizada por el Instituto [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1,108,27,239],"tags":[],"class_list":["post-5400","post","type-post","status-publish","format-standard","hentry","category-archives","category-bioeconomy","category-iefc-newsletter","category-non-wood-products"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["gb","fr","es","pt"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conferencia final de SustForest+: la resina tiene futuro - Instituto Europeo Del Bosque Cultivado - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conferencia final de SustForest+: la resina tiene futuro - Instituto Europeo Del Bosque Cultivado - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Europeo Del Bosque Cultivado - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-03T08:24:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:36:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2021\/12\/1-1024x768.jpg\" \/>\n<meta name=\"author\" content=\"comm IEFC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comm IEFC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/\"},\"author\":{\"name\":\"comm IEFC\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\"},\"headline\":\"Conferencia final de SustForest+: la resina tiene futuro\",\"datePublished\":\"2021-12-03T08:24:57+00:00\",\"dateModified\":\"2023-08-25T09:36:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/\"},\"wordCount\":2909,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/1-1024x768.jpg\",\"articleSection\":[\"\",\"Bioeconomia\",\"IEFC Newsletter\",\"Non Wood products\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/\",\"name\":\"Conferencia final de SustForest+: la resina tiene futuro - Instituto Europeo Del Bosque Cultivado - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/1-1024x768.jpg\",\"datePublished\":\"2021-12-03T08:24:57+00:00\",\"dateModified\":\"2023-08-25T09:36:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/1-1024x768.jpg\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/1-1024x768.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O projecto SustForest+ d\u00e1 um impulso \u00e0 produ\u00e7\u00e3o de resina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Instituto Europeo Del Bosque Cultivado - IEFC\",\"description\":\"La red para la gesti\u00f3n sostenible y la resiliencia de los bosques cultivados \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\",\"name\":\"comm IEFC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"caption\":\"comm IEFC\"},\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/es\\\/author\\\/communication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conferencia final de SustForest+: la resina tiene futuro - Instituto Europeo Del Bosque Cultivado - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/","og_locale":"es_ES","og_type":"article","og_title":"Conferencia final de SustForest+: la resina tiene futuro - Instituto Europeo Del Bosque Cultivado - IEFC","og_url":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/","og_site_name":"Instituto Europeo Del Bosque Cultivado - IEFC","article_published_time":"2021-12-03T08:24:57+00:00","article_modified_time":"2023-08-25T09:36:32+00:00","og_image":[{"url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2021\/12\/1-1024x768.jpg","type":"","width":"","height":""}],"author":"comm IEFC","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"Escrito por":"comm IEFC","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/"},"author":{"name":"comm IEFC","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a"},"headline":"Conferencia final de SustForest+: la resina tiene futuro","datePublished":"2021-12-03T08:24:57+00:00","dateModified":"2023-08-25T09:36:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/"},"wordCount":2909,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"image":{"@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2021\/12\/1-1024x768.jpg","articleSection":["","Bioeconomia","IEFC Newsletter","Non Wood products"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/","url":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/","name":"Conferencia final de SustForest+: la resina tiene futuro - Instituto Europeo Del Bosque Cultivado - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/#primaryimage"},"image":{"@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2021\/12\/1-1024x768.jpg","datePublished":"2021-12-03T08:24:57+00:00","dateModified":"2023-08-25T09:36:32+00:00","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/#primaryimage","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2021\/12\/1-1024x768.jpg","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2021\/12\/1-1024x768.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/pt\/conference-finale-sustforest-le-gemmage-a-le-vent-en-poupe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/"},{"@type":"ListItem","position":2,"name":"O projecto SustForest+ d\u00e1 um impulso \u00e0 produ\u00e7\u00e3o de resina"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Instituto Europeo Del Bosque Cultivado - IEFC","description":"La red para la gesti\u00f3n sostenible y la resiliencia de los bosques cultivados ","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a","name":"comm IEFC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","caption":"comm IEFC"},"url":"https:\/\/www.plantedforests.org\/es\/author\/communication\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/5400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/comments?post=5400"}],"version-history":[{"count":18,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/5400\/revisions"}],"predecessor-version":[{"id":5879,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/5400\/revisions\/5879"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/media?parent=5400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/categories?post=5400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/tags?post=5400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}