
{"id":4265,"date":"2020-12-22T11:42:46","date_gmt":"2020-12-22T10:42:46","guid":{"rendered":"https:\/\/www.iefc.net\/?p=4265"},"modified":"2023-08-25T11:36:36","modified_gmt":"2023-08-25T09:36:36","slug":"how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/es\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/","title":{"rendered":"\u00bfC\u00f3mo podemos acelerar los procesos de mejora de con\u00edferas \u00e9lite para el sector forestal?"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Utilizando la embriog\u00e9nesis som\u00e1tica para abastecer de forma competitiva de una mezcla de variedades mejor adaptadas a los efectos derivados del cambio clim\u00e1tico: el proyecto MULTIFOREVER desarrolla nuevas estrategias.<strong> <\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">En el actual contexto de cambio clim\u00e1tico y de estreses derivados del mismo, existe una creciente demanda de material forestal \u00e9lite; El proceso de selecci\u00f3n del mismo puede acelerarse mediante la obtenci\u00f3n\/selecci\u00f3n de variedades. En esta estrategia, las variedades seleccionadas se obtienen a trav\u00e9s de un proceso innovador, la embriog\u00e9nesis som\u00e1tica. Esta t\u00e9cnica permite evitar la demanda de semillas procedentes de los huertos semilleros convencionales. Este documento presenta las principales ideas e innovaciones obtenidas en el proyecto MULTIFOREVER y c\u00f3mo puede contribuir a abordar algunos de los desaf\u00edos reales del sector forestal.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Hacia la ordenaci\u00f3n sostenible de las plantaciones forestales productivas<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La\nproporci\u00f3n de bosque cultivado aumenta continuamente para hacer frente a la\ndemanda mundial de productos madereros (+ 50 % para 2050; FAO) y, por lo tanto,\npodr\u00eda ayudar significativamente a reducir la presi\u00f3n de tala sobre los bosques\nnativos. En esta situaci\u00f3n, las plantaciones de manejo intensivo se est\u00e1n\nconvirtiendo en la principal fuente de producci\u00f3n de madera en rollo (33 %). El\nr\u00e1pido crecimiento, la productividad y la adaptabilidad tanto a diversas\ncondiciones ecol\u00f3gicas como a los procesos industriales para su transformaci\u00f3n,\nhacen de las con\u00edferas las principales especies utilizadas en el bosque\ncultivado en la actualidad. Una de las principales claves para mantener la\nproductividad es invertir en la reproducci\u00f3n gen\u00e9tica de especies de gran valor\ncomo el pino, el alerce, el abeto Douglas o el abeto. Estas con\u00edferas todav\u00eda est\u00e1n\nen gran parte sin domesticar y tienen una diversidad gen\u00e9tica significativa en\nsus poblaciones naturales as\u00ed como en los bosques cultivados. Por lo tanto, se\npuede obtener una alta ganancia gen\u00e9tica para rasgos importantes despu\u00e9s de\ncada ciclo de reproducci\u00f3n. Pero este es un proceso bastante lento que requiere\nun sistema de alto rendimiento para la obtenci\u00f3n de variedades mejoradas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tradicionalmente,\nlas nuevas variedades se producen en huertos semilleros de polinizaci\u00f3n abierta\nmediante la reproducci\u00f3n sexual de \u00e1rboles seleccionados (silvicultura basada\nen semillas). Esta es una estrategia vers\u00e1til y de bajo costo, pero con un\nretraso significativo para alcanzar la madurez sexual de los progenitores de\nsemillas. Adem\u00e1s, la calidad se puede estimar a nivel familiar, siendo\ndesconocido el valor que tendr\u00e1n las plantas desarrolladas individualmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una\nestrategia alternativa y complementaria ser\u00eda multiplicar directamente\ncualquier \u00e1rbol seleccionado, replicando el genotipo del \u00e1rbol donador,\nmediante m\u00e9todos de propagaci\u00f3n vegetativa y asexual (propagaci\u00f3n clonal). De\nesta manera, el rendimiento de cada variedad se podr\u00eda determinar tanto a nivel\nfamiliar como individual (genotipo concreto). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/forestvalue.org\/wp-content\/uploads\/2020\/05\/MF_stakeholder_oriented_articlesNo1.pdf\">Una\ngran oportunidad para el futuro<\/a> es la utilizaci\u00f3n de la Silvicultura\nMultivarietal (MVF). Las principales ventajas de MVF sobre la silvicultura\nbasada en semillas es que se puede lograr una mayor ganancia gen\u00e9tica por ciclo\nde reproducci\u00f3n. Por lo tanto, los obtentores y cultivadores de \u00e1rboles se\nbenefician de una mayor flexibilidad para hacer frente a los cambiantes\nproblemas ambientales y socioecon\u00f3micos, introduciendo continuamente variedades\nmejor adaptadas. De forma m\u00e1s concreta, la MVF permite utilizar eficientemente la\ndiversidad gen\u00e9tica de variedades \u00e9lite propagadas a partir de clones\nseleccionados. Despu\u00e9s de haber definido la ganancia gen\u00e9tica asociada con\nmezclas de clones probados para un rasgo de inter\u00e9s, se puede establecer la\ndiversidad gen\u00e9tica necesaria en una plantaci\u00f3n utilizando una mezcla de clones\nde alto rendimiento y optimizando la combinaci\u00f3n de los mismos. As\u00ed es como la MVF\npuede contribuir al manejo sostenible de los bosques cultivados.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Herramienta de MULTIFOREVER: propagaci\u00f3n vegetativa de variedades de con\u00edferas mediante embriog\u00e9nesis som\u00e1tica<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La mejor\nalternativa de producci\u00f3n de planta es la propagaci\u00f3n vegetativa, pero cuando\nun \u00e1rbol ha mostrado los rasgos de inter\u00e9s ya ha cambiado de fase y por tanto\nha perdido\/minimizado su capacidad de ser reproducido de forma convencional\n(esquejes, etc.). <a href=\"https:\/\/youtu.be\/Qs0u0DygmUA\">MULTIFOREVER<\/a> se\ncentra en el desarrollo de la embriog\u00e9nesis som\u00e1tica (ES) como un poderoso\nm\u00e9todo alternativo de propagaci\u00f3n vegetativa (<em>in vitro<\/em>) para conseguir la propagaci\u00f3n eficiente de \u00e1rboles\nseleccionados. Actualmente, la tecnolog\u00edade ES m\u00e1s avanzada permite la\nmultiplicaci\u00f3n de embriones som\u00e1ticos (similares a las semillas) de forma\naltamente eficaz. Deben controlarse varios pasos, desde la iniciaci\u00f3n y\nmultiplicaci\u00f3n del tejido embriog\u00e9nico (embriones som\u00e1ticos inmaduros), hasta\nla producci\u00f3n de embriones maduros y la conversi\u00f3n en plantas som\u00e1ticas\nsimilares a las pl\u00e1ntulas procedentes de semillas convencionales. Una gran\nventaja del proceso de ES es que los tejidos embriog\u00e9nicos se pueden\ncriopreservar f\u00e1cilmente a temperaturas ultra bajas, mientras que las plantas\nsom\u00e1ticas obtenidas de estos tejidos se ensayan en el campo. Una vez que estas\nplantas han adquirido una determinada edad (variable en cada especie), pueden\nevaluarse y elegir los clones de alto rendimiento. En este punto, las masas\nembriog\u00e9nicas almacenadas pueden descongelarse, regenerarse tejido embriog\u00e9nico\ny someterse al proceso de maduraci\u00f3n de embriones som\u00e1ticos y de germinaci\u00f3n y\naclimataci\u00f3n de planta som\u00e1tica \u00e9lite. Por lo tanto, la ES permite poder\nutilizar recursos gen\u00e9ticos almacenados a demanda del sector forestal\nconoci\u00e9ndose de antemano el rendimiento que van a tener en campo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los\nesfuerzos internacionales de investigaci\u00f3n colaborativa orientada a la\naplicaci\u00f3n de estas t\u00e9cnicas en el marco del proyecto MULTIFOREVER, permitir\u00e1n\nel desarrollo de estrategias de selecci\u00f3n y optimizaci\u00f3n del proceso derivando\nen plantaciones forestales de \u00e1rboles \u00e9lite que muestren una adaptaci\u00f3n natural\no inducida al estr\u00e9s ambiental derivado del cambio clim\u00e1tico. En este sentido,\nse garantizar\u00e1 una producci\u00f3n continua de biomasa procedente de la madera.\nDentro del proyecto trabajamos con un abanico de especies de alto inter\u00e9s con\ns\u00f3lidos programas de mejora en Europa (Alerces europeos e h\u00edbridos, abeto\nnoruego, abeto Douglas, pino mar\u00edtimo, taeda y radiata) y Argentina (pino taeda\ne h\u00edbridos de pinos).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El objetivo general de MULTIFOREVER es desarrollar en la Uni\u00f3n Europea y Argentina una cadena de valor agregado y una estrategia conjunta para implantar la embriog\u00e9nesis som\u00e1tica como una forma de producci\u00f3n competitiva de \u00e1rboles de inter\u00e9s forestal que permita la implantaci\u00f3n de la silvicultura multivarietal. <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2127\" height=\"598\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_spanish.jpg\" alt=\"\" class=\"wp-image-4408\" srcset=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_spanish.jpg 2127w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_spanish-150x42.jpg 150w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_spanish-300x84.jpg 300w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_spanish-768x216.jpg 768w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_spanish-1024x288.jpg 1024w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_spanish-600x169.jpg 600w\" sizes=\"(max-width: 2127px) 100vw, 2127px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Algunos <\/strong><a href=\"https:\/\/forestvalue.org\/wp-content\/uploads\/2020\/11\/MULTIFOREVER_presentation_171120.pdf\"><strong>logros importantes del proyecto MULTIFOREVER<\/strong><\/a><strong>:<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de la situaci\u00f3n de bloqueo debido a la Covid-19, pudimos intercambiar plantas j\u00f3venes procedentes de embriog\u00e9nesis som\u00e1tica entre diferentes pa\u00edses y pudimos establecer <a href=\"https:\/\/forestvalue.org\/wp-content\/uploads\/2020\/08\/MF_stakeholder_oriented_articlesNo2.pdf\">parcelas demostrativas<\/a> de mezclas multiclonales y de semillas convencionales para varias especies de inter\u00e9s (abeto de Douglas, alerce h\u00edbrido, abeto de Noruega). <strong>Estos ensayos podr\u00edan constituir la primera experiencia europea de silvicultura multivarietal de con\u00edferas basada en ES<\/strong>. Con estos ensayos, esperamos llegar y concienciar a los silvicultures, productores de planta y propietarios forestales del potencia de esta estrategia en el actual escenario de cambio clim\u00e1tico. De este modo, podr\u00edamos acortar los ciclos de reproducci\u00f3n utilizando clones criopreservados procedentes de cruces controlados de progenitores seleccionados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, hemos avanzado en la optimizaci\u00f3n de los procesos de ES utilizando diversos enfoques:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I) Exponer a los embriones som\u00e1ticos a estr\u00e9s por temperatura en una etapa temprana (\u00abpriming\u00bb) para que desarrollen una memoria durante su desarrollo y exhiban posteriormente (en la etapa de crecimiento de las plantas) tolerancia a estreses abi\u00f3ticos como la sequ\u00eda. <a href=\"https:\/\/clicktime.symantec.com\/3CP4UaNb3fNTXiW1Y8ovtLm6H2?u=https%3A%2F%2Fforestvalue.org%2Fwp-content%2Fuploads%2F2020%2F12%2F2020_12_newsletter.pdf\">Se han obtenido resultados prometedores en pino radiata<\/a> que <strong>pueden ser de inter\u00e9s para introducirlo en los programas de mejora de esta especie que puedan ser \u00fatiles para mitigar los efectos del cambio clim\u00e1tico<\/strong>. Estos hallazgos han sido publicados en diversas revista cient\u00edficas y podr\u00e1n ser utilizados para desarrollar nuevas herramientas de mejora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">II) Tratar de reproducir exactamente el genotipo de \u00e1rbol donador propagando \u00e1rboles adultos. Con esta estrateg\u00eda podr\u00edamos propagar directamente \u00e1rboles que han mostrado resistencia a estreses bi\u00f3ticos y abi\u00f3ticos y <strong>se dispondr\u00eda de plantas en un periodo mucho m\u00e1s corto<\/strong>. En este sentido, se ha logrado la propagaci\u00f3n de abetos adultos utilizando yemas vegetativas (<a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fpls.2018.01551\/full\">Varis et al. 2018<\/a>); en la actualidad estamos estudiando los factores gen\u00e9ticos que afectan a la iniciaci\u00f3n del tejido embriog\u00e9nico para poder comprender mejor que factores est\u00e1n involucrados en el proceso y llegar a poder manipularlo en el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">III) Optimizar algunas etapas de la ES para minimizar los costes asociados a las mismas en el laboratorio. Se est\u00e1n escalando los procesos a bioreactores para que sean m\u00e1s eficaces y se pueda llegar a automatizar reduciendo la mano de obra en algunos pasos. <strong>Se espera reducir los costes asociados a la producci\u00f3n <em>in vitro<\/em> de estas plantas som\u00e1ticas \u00e9lite haci\u00e9ndolos competitivos<\/strong> respecto a la producci\u00f3n de planta de forma convencional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9reis conocer m\u00e1s detalles? Por favor, \u00a1contacta con nosotros!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andrea Rupps (<a href=\"mailto:andrea.rupps@hu-berlin.de\">andrea.rupps@hu-berlin.de<\/a>) y Jean-Fran\u00e7ois Trontin (<a href=\"mailto:jean-francois.trontin@fcba.fr\">jean-francois.trontin@fcba.fr<\/a>) Co-coordinadores del proyecto MULTIFOREVER<\/p>\n\n\n<p><!--EndFragment--><br>\n<br>\n<\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" width=\"300\" height=\"179\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER-Logo-300x179.jpg\" alt=\"\" class=\"wp-image-4346\" srcset=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER-Logo-300x179.jpg 300w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER-Logo-150x90.jpg 150w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER-Logo.jpg 594w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n<p><!--EndFragment--><\/p>\n<p style=\"text-align: center;\"><strong><em>Hacia la intensificaci\u00f3n de la producci\u00f3n de con\u00edferas a trav\u00e9s de la silvicultura multivarietal basada en la embriog\u00e9nesis som\u00e1tica<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/multiforever.com\/\">https:\/\/multiforever.com\/<\/a><\/p>\n<p style=\"text-align: center;\"><em>(en construcci\u00f3n)<\/em><\/p>\n<p style=\"text-align: center;\"><em>MULTIFOREVER es un Consorcio nacido de las actividades de la <\/em><a href=\"https:\/\/www.iufro.org\/science\/divisions\/division-2\/20000\/20900\/20902\/\"><em>unidad de IUFRO <\/em>2.09.02<\/a><em>.<br \/><\/em><em>Engloba a 7 equipos de expertos en la embriog\u00e9nesis som\u00e1tica de con\u00edferas de 6 pa\u00edses europeas y Argentina. <\/em><\/p>\n<p><!--EndFragment--><\/p>\n\n\n<table class=\"wp-block-table\"><tbody><tr><td><div class=\"wp-block-image\"><figure class=\"alignleft\"><strong>Francia<\/strong><\/figure><\/div><br><\/td><td><strong>Alemania<\/strong><\/td><td><strong>Argentina<\/strong><\/td><td><strong>Finlandia<\/strong><\/td><td><strong>Espa\u00f1a<\/strong><\/td><td><strong>Suecia<\/strong><\/td><\/tr><tr><td><figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Logo-INRAE-FCBA-1024x1024.jpg\" alt=\"\" class=\"wp-image-4371\" width=\"100\" height=\"100\" srcset=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Logo-INRAE-FCBA-1024x1024.jpg 1024w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Logo-INRAE-FCBA-150x150.jpg 150w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Logo-INRAE-FCBA-300x300.jpg 300w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Logo-INRAE-FCBA-768x768.jpg 768w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Logo-INRAE-FCBA-600x600.jpg 600w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Logo-INRAE-FCBA.jpg 1450w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/figure><\/td><td><figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Allemagne.gif\" alt=\"\" class=\"wp-image-4367\" width=\"100\" height=\"100\"><\/figure><\/td><td><figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Argentine.gif\" alt=\"\" class=\"wp-image-4368\" width=\"100\" height=\"100\"><\/figure><\/td><td><figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Finlande.jpg\" alt=\"\" class=\"wp-image-4369\" width=\"100\" height=\"100\"><\/figure><\/td><td><figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Espagne.jpg\" alt=\"\" class=\"wp-image-4372\" width=\"100\" height=\"100\"><\/figure><\/td><td><figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/Su\u00e8de.png\" alt=\"\" class=\"wp-image-4370\" width=\"100\" height=\"100\"><\/figure><\/td><\/tr><tr><td> <a href=\"mailto:jean-francois.trontin@fcba.fr\">J.-F. Trontin<\/a><br> <a href=\"mailto:marie-anne.lelu-walter@inrae.fr\">M.-A. Lelu-Walter<\/a> <br><\/td><td> <a href=\"mailto:andrea.rupps@hu-berlin.de\">A. Rupps<\/a> <\/td><td> <a href=\"mailto:gauchat.maria@.inta.gob.ar\">M.A. Gauchat<\/a> <\/td><td><a href=\"mailto:tuija.aronen@luke.fi\">T. Aronen<\/a> <\/td><td><a href=\"mailto:pmoncalean@neiker.eus\">P. Moncale\u00e1n<\/a> <\/td><td><a href=\"mailto:Ulrika.Egertsdotter@slu.se\">U. Egertsdotter<\/a> <\/td><\/tr><\/tbody><\/table>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El Proyecto MULTIFOREVER se financia a trav\u00e9s de los\nfondos cofinanciados ERA-NET \u2018ForestValue \u2013 Innovating forest-based bioeconomy\u2019\nde ANR (FR), FNR (DE), MINCyT (AR), MINECO-AEI (ES), MMM (FI) y VINNOVA (SE). <\/em><a href=\"https:\/\/forestvalue.org\/\"><em>ForestValue<\/em><\/a><em> ha\nrecibido financiaci\u00f3n del programa Horizon 2020 de la Uni\u00f3n Europea y del\nprograma de innovaci\u00f3n N\u00b0773324.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autores: Jean-Francois Trontin (FCBA), Juliane Raschke (HUB), Paloma Moncale\u00e1n (NEIKER), Andrea Rupps (HUB).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Utilizando la embriog\u00e9nesis som\u00e1tica para abastecer de forma competitiva de una mezcla de variedades mejor adaptadas a los efectos derivados del cambio clim\u00e1tico: el proyecto MULTIFOREVER desarrolla nuevas estrategias. En [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1,229,241,27],"tags":[],"class_list":["post-4265","post","type-post","status-publish","format-standard","hentry","category-archives","category-genetic-ressources","category-breeding","category-iefc-newsletter"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"es","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo podemos acelerar los procesos de mejora de con\u00edferas \u00e9lite para el sector forestal? - Instituto Europeo Del Bosque Cultivado - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo podemos acelerar los procesos de mejora de con\u00edferas \u00e9lite para el sector forestal? - Instituto Europeo Del Bosque Cultivado - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Europeo Del Bosque Cultivado - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-22T10:42:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_english.jpg\" \/>\n<meta name=\"author\" content=\"comm IEFC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comm IEFC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"24 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/\"},\"author\":{\"name\":\"comm IEFC\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\"},\"headline\":\"\u00bfC\u00f3mo podemos acelerar los procesos de mejora de con\u00edferas \u00e9lite para el sector forestal?\",\"datePublished\":\"2020-12-22T10:42:46+00:00\",\"dateModified\":\"2023-08-25T09:36:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/\"},\"wordCount\":4975,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/MULTIFOREVER_fig_english.jpg\",\"articleSection\":[\"\",\"Recursos geneticos\",\"Breeding\",\"IEFC Newsletter\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/\",\"name\":\"\u00bfC\u00f3mo podemos acelerar los procesos de mejora de con\u00edferas \u00e9lite para el sector forestal? - Instituto Europeo Del Bosque Cultivado - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/MULTIFOREVER_fig_english.jpg\",\"datePublished\":\"2020-12-22T10:42:46+00:00\",\"dateModified\":\"2023-08-25T09:36:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/MULTIFOREVER_fig_english.jpg\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/MULTIFOREVER_fig_english.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How to accelerate breeding and afforestation efforts with valuable conifers?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Instituto Europeo Del Bosque Cultivado - IEFC\",\"description\":\"La red para la gesti\u00f3n sostenible y la resiliencia de los bosques cultivados \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\",\"name\":\"comm IEFC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"caption\":\"comm IEFC\"},\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/es\\\/author\\\/communication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo podemos acelerar los procesos de mejora de con\u00edferas \u00e9lite para el sector forestal? - Instituto Europeo Del Bosque Cultivado - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo podemos acelerar los procesos de mejora de con\u00edferas \u00e9lite para el sector forestal? - Instituto Europeo Del Bosque Cultivado - IEFC","og_url":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/","og_site_name":"Instituto Europeo Del Bosque Cultivado - IEFC","article_published_time":"2020-12-22T10:42:46+00:00","article_modified_time":"2023-08-25T09:36:36+00:00","og_image":[{"url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_english.jpg","type":"","width":"","height":""}],"author":"comm IEFC","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"Escrito por":"comm IEFC","Tiempo de lectura":"24 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/"},"author":{"name":"comm IEFC","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a"},"headline":"\u00bfC\u00f3mo podemos acelerar los procesos de mejora de con\u00edferas \u00e9lite para el sector forestal?","datePublished":"2020-12-22T10:42:46+00:00","dateModified":"2023-08-25T09:36:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/"},"wordCount":4975,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"image":{"@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_english.jpg","articleSection":["","Recursos geneticos","Breeding","IEFC Newsletter"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/","url":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/","name":"\u00bfC\u00f3mo podemos acelerar los procesos de mejora de con\u00edferas \u00e9lite para el sector forestal? - Instituto Europeo Del Bosque Cultivado - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/#primaryimage"},"image":{"@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_english.jpg","datePublished":"2020-12-22T10:42:46+00:00","dateModified":"2023-08-25T09:36:36+00:00","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/#primaryimage","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_english.jpg","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2020\/12\/MULTIFOREVER_fig_english.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/how-to-accelerate-breeding-and-afforestation-efforts-with-valuable-conifers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/fr\/"},{"@type":"ListItem","position":2,"name":"How to accelerate breeding and afforestation efforts with valuable conifers?"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Instituto Europeo Del Bosque Cultivado - IEFC","description":"La red para la gesti\u00f3n sostenible y la resiliencia de los bosques cultivados ","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a","name":"comm IEFC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","caption":"comm IEFC"},"url":"https:\/\/www.plantedforests.org\/es\/author\/communication\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/4265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/comments?post=4265"}],"version-history":[{"count":43,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/4265\/revisions"}],"predecessor-version":[{"id":4431,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/4265\/revisions\/4431"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/media?parent=4265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/categories?post=4265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/tags?post=4265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}