
{"id":2694,"date":"2009-07-17T13:09:55","date_gmt":"2009-07-17T11:09:55","guid":{"rendered":"https:\/\/www.iefc.net\/?p=2694"},"modified":"2023-08-25T11:37:23","modified_gmt":"2023-08-25T09:37:23","slug":"demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/es\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/","title":{"rendered":"Tormentas destructivas en Europa: su impacto en el pasado y gesti\u00f3n futura."},"content":{"rendered":"<p>STORM significa tormenta en ingl\u00e9s y es el nombre del informe Europeo FP7-ENV.B1\/ETU\/2009 con t\u00edtulo \u00ab\u00a0Tormentas destructivas en los bosques Europeo, impactos pasados y futuros\u00a0\u00bb. Este informe comenz\u00f3 el pasado 22 de Octubre y durar\u00e1 9 meses, su presupuesto es de 149\u00a0721 \u0080. El consorcio se encuentra liderado por EFIAtlantic contando con la colaboraci\u00f3n de las Oficinas Centrales y de otra oficina regional del EFI, EFICENT (Finlandia, Francia, Reino Unido, Alemania, Suiza) , junto a tres subcontratados (ALTERRA, Holanda, GIP Ecofor, Francia y SLU, Suecia) y un experto externo (National Park, Eslovaquia). Este proyecto es un intento de comprender la naturaleza del riesgo de los da\u00f1os producidos por viento en los bosques Europeos, y como este riesgo podr\u00eda cambiar los impactos sociales, medio ambientales y econ\u00f3micos de este tipo de perturbaci\u00f3n. Asi mismo analizar\u00e1 el papel que diferentes pol\u00edticas pueden jugar en reducir ese riesgo y acelerar la recuperaci\u00f3n despu\u00e9s de estos episodios de da\u00f1os por viento.<br \/>\nPrincipalmente intentaremos conseguir los siguientes aspectos.<\/p>\n<ul>\n<li>La clasificaci\u00f3n de las tormentas seg\u00fan su impacto en los bosques Europeos de una manera consistente, creando un m\u00e9todo estandarizado, que pueda ser usado a lo largo de Europa<\/li>\n<li>El uso de esta clasificaci\u00f3n para resumir el impacto de las tormentas a lo largo de los recursos forestales de los pa\u00edses de la UE durante los \u00faltimos 50 a\u00f1os y la identificaci\u00f3n de las 30 tormentas m\u00e1s destructivas<\/li>\n<li>Para una selecci\u00f3n de 10 tormentas recopilar su impacto ecol\u00f3gico, social y econ\u00f3mico<\/li>\n<li>La identificaci\u00f3n entre los da\u00f1os de las tormentas y el estado de los recursos forestales con anterioridad a la tormenta, para poder identificar los factores, que m\u00e1s influyen en la gravedad de los da\u00f1os de la tormenta<\/li>\n<li>La documentaci\u00f3n de las repercusiones positivas y negativas, que las decisiones posteriores a las tormentas a lo largo de Europa, y producir \u00ab\u00a0blueprint\u00a0\u00bb un mix pol\u00edtico efectivo, que pueda gestionar los da\u00f1os de viento severos<\/li>\n<li>La realizaci\u00f3n de la mejor estimaci\u00f3n posible de los da\u00f1os por viento dentro de un escenario con un clima cambiante para los recursos forestales Europeos. Adem\u00e1s de dar respuesta al impacto, que las diferentes perturbaciones en los suelos forestales, que suceden tras un episodio de da\u00f1o por viento y como influyen en la emisi\u00f3n de gases de efecto invernadero<\/li>\n<li>Dar respuesta a las futuras consequencias, que la decisi\u00f3n de no realizar cambios sobre el plantamiento actual a la gesti\u00f3n de los da\u00f1os producidos por el viento, tendr\u00eda tanto a nivel Europeo, Nacional como Regional<\/li>\n<li>El desarrollar un estrategia para la implementaci\u00f3n de la legislaciones referidas a la mitigaci\u00f3n de los impactos de las tormentas sobre los bosques Europeos y de una posible y r\u00e1pida recuperaci\u00f3n tras las mismas, a lo largo de Europa<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>STORM significa tormenta en ingl\u00e9s y es el nombre del informe Europeo FP7-ENV.B1\/ETU\/2009 con t\u00edtulo \u00ab\u00a0Tormentas destructivas en los bosques Europeo, impactos pasados y futuros\u00a0\u00bb. Este informe comenz\u00f3 el pasado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1,27],"tags":[],"class_list":["post-2694","post","type-post","status-publish","format-standard","hentry","category-archives","category-iefc-newsletter"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"es","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tormentas destructivas en Europa: su impacto en el pasado y gesti\u00f3n futura. - Instituto Europeo Del Bosque Cultivado - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tormentas destructivas en Europa: su impacto en el pasado y gesti\u00f3n futura. - Instituto Europeo Del Bosque Cultivado - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Europeo Del Bosque Cultivado - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-17T11:09:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:37:23+00:00\" \/>\n<meta name=\"author\" content=\"Christophe Orazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christophe Orazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\\\/\"},\"author\":{\"name\":\"Christophe Orazio\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b18e9ff19844f867cee76d11998f187\"},\"headline\":\"Tormentas destructivas en Europa: su impacto en el pasado y gesti\u00f3n futura.\",\"datePublished\":\"2009-07-17T11:09:55+00:00\",\"dateModified\":\"2023-08-25T09:37:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\\\/\"},\"wordCount\":1244,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"articleSection\":[\"\",\"IEFC Newsletter\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\\\/\",\"name\":\"Tormentas destructivas en Europa: su impacto en el pasado y gesti\u00f3n futura. - Instituto Europeo Del Bosque Cultivado - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"datePublished\":\"2009-07-17T11:09:55+00:00\",\"dateModified\":\"2023-08-25T09:37:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destructive storms in European forests : past and forthcoming impacts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Instituto Europeo Del Bosque Cultivado - IEFC\",\"description\":\"La red para la gesti\u00f3n sostenible y la resiliencia de los bosques cultivados \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b18e9ff19844f867cee76d11998f187\",\"name\":\"Christophe Orazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g\",\"caption\":\"Christophe Orazio\"},\"sameAs\":[\"http:\\\/\\\/christophe-orazio.alwaysdata.net\\\/page_perso\\\/curriculum-vitae-cv\\\/\"],\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/es\\\/author\\\/c-orazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tormentas destructivas en Europa: su impacto en el pasado y gesti\u00f3n futura. - Instituto Europeo Del Bosque Cultivado - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/","og_locale":"es_ES","og_type":"article","og_title":"Tormentas destructivas en Europa: su impacto en el pasado y gesti\u00f3n futura. - Instituto Europeo Del Bosque Cultivado - IEFC","og_url":"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/","og_site_name":"Instituto Europeo Del Bosque Cultivado - IEFC","article_published_time":"2009-07-17T11:09:55+00:00","article_modified_time":"2023-08-25T09:37:23+00:00","author":"Christophe Orazio","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"Escrito por":"Christophe Orazio","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/"},"author":{"name":"Christophe Orazio","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/6b18e9ff19844f867cee76d11998f187"},"headline":"Tormentas destructivas en Europa: su impacto en el pasado y gesti\u00f3n futura.","datePublished":"2009-07-17T11:09:55+00:00","dateModified":"2023-08-25T09:37:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/"},"wordCount":1244,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"articleSection":["","IEFC Newsletter"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/","url":"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/","name":"Tormentas destructivas en Europa: su impacto en el pasado y gesti\u00f3n futura. - Instituto Europeo Del Bosque Cultivado - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"datePublished":"2009-07-17T11:09:55+00:00","dateModified":"2023-08-25T09:37:23+00:00","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/demarrage-de-lexpertise-europeenne-7eme-pcrd-env-b1-etu-2009-sur-les-tempetes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Destructive storms in European forests : past and forthcoming impacts"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Instituto Europeo Del Bosque Cultivado - IEFC","description":"La red para la gesti\u00f3n sostenible y la resiliencia de los bosques cultivados ","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/6b18e9ff19844f867cee76d11998f187","name":"Christophe Orazio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/631f0d47d74ce826d7ca4f0576f716b2a078fbf8c64b6c8e63943bb28118fd2e?s=96&d=identicon&r=g","caption":"Christophe Orazio"},"sameAs":["http:\/\/christophe-orazio.alwaysdata.net\/page_perso\/curriculum-vitae-cv\/"],"url":"https:\/\/www.plantedforests.org\/es\/author\/c-orazio\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/2694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/comments?post=2694"}],"version-history":[{"count":3,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/2694\/revisions"}],"predecessor-version":[{"id":10803,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/2694\/revisions\/10803"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/media?parent=2694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/categories?post=2694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/tags?post=2694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}