
{"id":14934,"date":"2024-01-15T09:00:06","date_gmt":"2024-01-15T08:00:06","guid":{"rendered":"https:\/\/www.plantedforests.org\/?p=14934"},"modified":"2024-01-24T14:35:15","modified_gmt":"2024-01-24T13:35:15","slug":"fire-res-general-meeting","status":"publish","type":"post","link":"https:\/\/www.plantedforests.org\/es\/fire-res-general-meeting\/","title":{"rendered":"Reuni\u00f3n general de FIRE-RES: Uniendo fuerzas para lograr paisajes resilientes frente a los incendios forestales"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color wp-block-paragraph\">El proyecto FIRE-RES concluy\u00f3 recientemente una fruct\u00edfera Reuni\u00f3n General entre el 7 y el 9 de noviembre, en la que se forj\u00f3 un esfuerzo conjunto para abordar los retos de los incendios forestales y aumentar la resiliencia de los paisajes frente a los incendios.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">El primer d\u00eda, que comenz\u00f3 con una c\u00e1lida bienvenida y presentaciones institucionales por parte de ISA, FWISE y AFVS, sent\u00f3 las bases para las interesantes sesiones que siguieron. Los responsables de los paquetes de trabajo del CTFC compartieron con nosotros sus hojas de ruta en sinton\u00eda con los objetivos del proyecto, al tiempo que analizaban el problema de la comprensi\u00f3n de los Incendios Forestales Extremos (EWE, por sus siglas en ingl\u00e9s), que son aquellos que superan la capacidad de control actual. Tambi\u00e9n destacaron su papel en el desarrollo de paisajes resilientes. Expertos como Zisoula Ntasiou, Mart\u00ed Rosell y Teresa Valor compartieron experiencias impactantes y ense\u00f1anzas inestimables, sentando las bases para los debates posteriores.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"422\" height=\"317\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2.jpg\" alt=\"\" class=\"wp-image-14935\" srcset=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2.jpg 422w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2-300x225.jpg 300w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2-150x113.jpg 150w\" sizes=\"(max-width: 422px) 100vw, 422px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><span style=\"text-decoration: underline;\">Presentaci\u00f3n informativa de los objetivos del proyecto durante la Asamblea General de FIRE-RES<\/span><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">El segundo d\u00eda, el viaje continu\u00f3 m\u00e1s all\u00e1 de los muros de las salas de reuniones. Una excursi\u00f3n a Penafiel se convirti\u00f3 en una exploraci\u00f3n, mostrando aplicaciones pr\u00e1cticas de la gesti\u00f3n forestal en tres paradas diferentes: la primera en REN (Redes Energ\u00e9ticas Nacionais), donde se abordaron los cortafuegos instalados bajo las l\u00edneas el\u00e9ctricas; otra en Quinta Aveleda, donde se exploraron los sistemas de subvenciones que promueven los cambios de uso del suelo en zonas muy propensas a los incendios; y, por \u00faltimo, otra en la \u00abIsla de la Biodiversidad\u00bb, Fonte Arcada, donde se demostraron los beneficios para la biodiversidad derivados de la plantaci\u00f3n de setos de frondosas para mitigar el riesgo de incendios.<\/p>\n\n\n\n<div style=\"height:7px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img decoding=\"async\" width=\"912\" height=\"684\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image2.jpg\" alt=\"\" class=\"wp-image-14936\" style=\"aspect-ratio:1.3333333333333333;width:422px;height:auto\" srcset=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image2.jpg 912w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image2-300x225.jpg 300w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image2-150x113.jpg 150w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image2-768x576.jpg 768w\" sizes=\"(max-width: 912px) 100vw, 912px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><span style=\"text-decoration: underline;\">Parada sobre el terreno para descubrir las alternativas de bioeconom\u00eda de la Isla de la Biodiversidad<\/span><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Esta exploraci\u00f3n est\u00e1 en consonancia con los trabajos del Living Lab de Nouvelle-Aquitaine: una colaboraci\u00f3n entre el IEFC (Instituto Europeo de Bosques Plantados), el INRAE (Instituto Nacional de Investigaci\u00f3n en Agronom\u00eda y Medio Ambiente) y el SDIS (Servicio Regional de Incendios y Salvamento) ha permitido elaborar un mapa de riesgo de incendios de la regi\u00f3n mediante la modelizaci\u00f3n, la mejora de la cartograf\u00eda de combustibles y la simulaci\u00f3n de la propagaci\u00f3n de incendios forestales. El objetivo de este trabajo es promover la reorganizaci\u00f3n del uso del suelo para que el paisaje sea m\u00e1s resiliente frente a los incendios. El IEFC y la ARDFCI tambi\u00e9n colaboran con los municipios locales (SYBARVAL, PaysBARVAL, PNR Landes de Gascogne, ONF&#8230;) para mejorar su planificaci\u00f3n urbana en un contexto de cambio clim\u00e1tico. Todos estos socios podr\u00edan reunirse durante la \u00faltima reuni\u00f3n del comit\u00e9 de innovaci\u00f3n del Living Lab el 26 de septiembre de 2023.<\/p>\n\n\n\n<div style=\"height:8px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img decoding=\"async\" width=\"842\" height=\"631\" src=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image3.jpg\" alt=\"\" class=\"wp-image-14938\" style=\"aspect-ratio:1.3343898573692552;width:523px;height:auto\" srcset=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image3.jpg 842w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image3-300x225.jpg 300w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image3-150x112.jpg 150w, https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image3-768x576.jpg 768w\" sizes=\"(max-width: 842px) 100vw, 842px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\"><span style=\"text-decoration: underline;\">Reuni\u00f3n del comit\u00e9 de innovaci\u00f3n en Mimizan el 26 de septiembre de 2023<\/span><\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Tras esta visita a Portugal, la participaci\u00f3n de las partes interesadas ocup\u00f3 un lugar central en una mesa redonda y en entrevistas con los medios de comunicaci\u00f3n, destacando la importancia de la acci\u00f3n colectiva. La jornada culmin\u00f3 con un amplio debate en el que se combinaron las iniciativas sobre el terreno y los avances tecnol\u00f3gicos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">El \u00faltimo d\u00eda, la atenci\u00f3n se centr\u00f3 en la presentaci\u00f3n de informes sobre los avances y los principales resultados en diversos \u00e1mbitos, bajo la direcci\u00f3n de los responsables de los grupos de trabajo. El Living Lab b\u00falgaro y griego present\u00f3 un magn\u00edfico ejemplo de resultados tecnol\u00f3gicos clave, consistente en el uso de un simulador del comportamiento de los incendios, junto con sistemas de apoyo a la toma de decisiones, para dise\u00f1ar soluciones de mitigaci\u00f3n de riesgos a corto plazo. Otro ejemplo que puede citarse es la estrategia de comunicaci\u00f3n entre los grandes propietarios forestales, que hace posible la gesti\u00f3n a nivel de paisaje, lo que se espera que tenga un impacto significativo. El equipo TEC del INESC tambi\u00e9n destac\u00f3 los progresos realizados en la utilizaci\u00f3n de sensores de humo port\u00e1tiles para aumentar la seguridad de los bomberos.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color wp-block-paragraph\">Al cierre de este cap\u00edtulo, el compromiso colectivo y los enfoques innovadores expuestos iluminan el camino hacia unos paisajes resilientes frente a la amenaza de los incendios forestales. Est\u00e1 previsto que la pr\u00f3xima reuni\u00f3n general se celebre en el Living Lab de Nouvelle-Aquitaine en 2024, as\u00ed que permanezcan atentos a las novedades que se produzcan a medida que el proyecto FIRE-RES contin\u00fae su viaje hacia la innovaci\u00f3n y la resiliencia.<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#006633\"><em>Lucas Moreews, Ingeniero forestal del Instituto Europeo Del Bosque Cultivado<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto FIRE-RES concluy\u00f3 recientemente una fruct\u00edfera Reuni\u00f3n General entre el 7 y el 9 de noviembre, en la que se forj\u00f3 un esfuerzo conjunto para abordar los retos de [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":14935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1,310],"tags":[],"class_list":["post-14934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives","category-january-2024"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"es","enabled_languages":["gb","fr","pt","es"],"languages":{"gb":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reuni\u00f3n general de FIRE-RES: Uniendo fuerzas para lograr paisajes resilientes frente a los incendios forestales - Instituto Europeo Del Bosque Cultivado - IEFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reuni\u00f3n general de FIRE-RES: Uniendo fuerzas para lograr paisajes resilientes frente a los incendios forestales - Instituto Europeo Del Bosque Cultivado - IEFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Europeo Del Bosque Cultivado - IEFC\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-15T08:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T13:35:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"422\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comm IEFC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:site\" content=\"@IEFCPlantForest\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comm IEFC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/\"},\"author\":{\"name\":\"comm IEFC\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\"},\"headline\":\"Reuni\u00f3n general de FIRE-RES: Uniendo fuerzas para lograr paisajes resilientes frente a los incendios forestales\",\"datePublished\":\"2024-01-15T08:00:06+00:00\",\"dateModified\":\"2024-01-24T13:35:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/\"},\"wordCount\":3080,\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Image1-2.jpg\",\"articleSection\":[\"\",\"January 2024\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/\",\"name\":\"Reuni\u00f3n general de FIRE-RES: Uniendo fuerzas para lograr paisajes resilientes frente a los incendios forestales - Instituto Europeo Del Bosque Cultivado - IEFC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Image1-2.jpg\",\"datePublished\":\"2024-01-15T08:00:06+00:00\",\"dateModified\":\"2024-01-24T13:35:15+00:00\",\"description\":\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Image1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Image1-2.jpg\",\"width\":422,\"height\":317},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/pt\\\/fire-res-general-meeting\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reuni\u00e3o Geral do FIRE-RES: Unindo For\u00e7as para Paisagens Resilientes contra Inc\u00eandios Florestais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"name\":\"Instituto Europeo Del Bosque Cultivado - IEFC\",\"description\":\"La red para la gesti\u00f3n sostenible y la resiliencia de los bosques cultivados \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#organization\",\"name\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"contentUrl\":\"https:\\\/\\\/www.plantedforests.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo_iefc__FR.png\",\"width\":2031,\"height\":1001,\"caption\":\"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org\"},\"image\":{\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IEFCPlantForest\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/71728047\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.plantedforests.org\\\/fr\\\/#\\\/schema\\\/person\\\/edbedd9ad5af1dac7dc652a454c1410a\",\"name\":\"comm IEFC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g\",\"caption\":\"comm IEFC\"},\"url\":\"https:\\\/\\\/www.plantedforests.org\\\/es\\\/author\\\/communication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reuni\u00f3n general de FIRE-RES: Uniendo fuerzas para lograr paisajes resilientes frente a los incendios forestales - Instituto Europeo Del Bosque Cultivado - IEFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/","og_locale":"es_ES","og_type":"article","og_title":"Reuni\u00f3n general de FIRE-RES: Uniendo fuerzas para lograr paisajes resilientes frente a los incendios forestales - Instituto Europeo Del Bosque Cultivado - IEFC","og_url":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/","og_site_name":"Instituto Europeo Del Bosque Cultivado - IEFC","article_published_time":"2024-01-15T08:00:06+00:00","article_modified_time":"2024-01-24T13:35:15+00:00","og_image":[{"width":422,"height":317,"url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2.jpg","type":"image\/jpeg"}],"author":"comm IEFC","twitter_card":"summary_large_image","twitter_creator":"@IEFCPlantForest","twitter_site":"@IEFCPlantForest","twitter_misc":{"Escrito por":"comm IEFC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/#article","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/"},"author":{"name":"comm IEFC","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a"},"headline":"Reuni\u00f3n general de FIRE-RES: Uniendo fuerzas para lograr paisajes resilientes frente a los incendios forestales","datePublished":"2024-01-15T08:00:06+00:00","dateModified":"2024-01-24T13:35:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/"},"wordCount":3080,"publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"image":{"@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2.jpg","articleSection":["","January 2024"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/","url":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/","name":"Reuni\u00f3n general de FIRE-RES: Uniendo fuerzas para lograr paisajes resilientes frente a los incendios forestales - Instituto Europeo Del Bosque Cultivado - IEFC","isPartOf":{"@id":"https:\/\/www.plantedforests.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/#primaryimage"},"image":{"@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2.jpg","datePublished":"2024-01-15T08:00:06+00:00","dateModified":"2024-01-24T13:35:15+00:00","description":"","breadcrumb":{"@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/#primaryimage","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2.jpg","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2023\/12\/Image1-2.jpg","width":422,"height":317},{"@type":"BreadcrumbList","@id":"https:\/\/www.plantedforests.org\/pt\/fire-res-general-meeting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.plantedforests.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Reuni\u00e3o Geral do FIRE-RES: Unindo For\u00e7as para Paisagens Resilientes contra Inc\u00eandios Florestais"}]},{"@type":"WebSite","@id":"https:\/\/www.plantedforests.org\/fr\/#website","url":"https:\/\/www.plantedforests.org\/fr\/","name":"Instituto Europeo Del Bosque Cultivado - IEFC","description":"La red para la gesti\u00f3n sostenible y la resiliencia de los bosques cultivados ","publisher":{"@id":"https:\/\/www.plantedforests.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantedforests.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.plantedforests.org\/fr\/#organization","name":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org","url":"https:\/\/www.plantedforests.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","contentUrl":"https:\/\/www.plantedforests.org\/wp-content\/uploads\/2022\/07\/Logo_iefc__FR.png","width":2031,"height":1001,"caption":"Institut Europ\u00e9en de la For\u00eat Cultiv\u00e9e - Plantedforests.org"},"image":{"@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IEFCPlantForest","https:\/\/www.linkedin.com\/company\/71728047\/"]},{"@type":"Person","@id":"https:\/\/www.plantedforests.org\/fr\/#\/schema\/person\/edbedd9ad5af1dac7dc652a454c1410a","name":"comm IEFC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23a934dab4d2ee2810151345aacad2ee727f418ca47a8610892f336a4f255a11?s=96&d=identicon&r=g","caption":"comm IEFC"},"url":"https:\/\/www.plantedforests.org\/es\/author\/communication\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/14934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/comments?post=14934"}],"version-history":[{"count":56,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/14934\/revisions"}],"predecessor-version":[{"id":15866,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/posts\/14934\/revisions\/15866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/media\/14935"}],"wp:attachment":[{"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/media?parent=14934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/categories?post=14934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantedforests.org\/es\/wp-json\/wp\/v2\/tags?post=14934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}